{"id":249340,"date":"2023-03-10T10:41:44","date_gmt":"2023-03-10T09:41:44","guid":{"rendered":"https:\/\/estudioaequus.com\/about-us\/"},"modified":"2024-01-29T12:16:53","modified_gmt":"2024-01-29T11:16:53","slug":"about-us","status":"publish","type":"page","link":"https:\/\/estudioaequus.com\/en\/about-us\/","title":{"rendered":"About us"},"content":{"rendered":"[et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|phone&#8221; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; background_enable_color=&#8221;off&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_stops=&#8221;#ffffff 0%|rgba(0,0,0,0.3) 100%&#8221; background_image=&#8221;https:\/\/estudioaequus.com\/wp-content\/uploads\/2023\/03\/centro-de-salud-corporal-aequus-estudio.jpg&#8221; background_blend=&#8221;multiply&#8221; custom_padding=&#8221;80px||80px||true|false&#8221; custom_padding_tablet=&#8221;350px||250px||false|false&#8221; custom_padding_phone=&#8221;50px||50px||true|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; width=&#8221;95%&#8221; max_width=&#8221;95%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;|700|||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_font_size=&#8221;74px&#8221; header_font=&#8221;|600||on|||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#FFFFFF&#8221; header_font_size=&#8221;64px&#8221; text_orientation=&#8221;center&#8221; text_font_size_tablet=&#8221;74px&#8221; text_font_size_phone=&#8221;40px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; header_font_size_tablet=&#8221;74px&#8221; header_font_size_phone=&#8221;30px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221; content_font_size_tablet=&#8221;74px&#8221; content_font_size_phone=&#8221;40px&#8221; content_font_size_last_edited=&#8221;on|phone&#8221;]\n<h1>Who we are<\/h1>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; background_image=&#8221;https:\/\/estudioaequus.com\/wp-content\/uploads\/2022\/09\/h6-bckr-1.jpeg&#8221; background_size=&#8221;contain&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;2_3,1_3&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; width=&#8221;85%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;2_3&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Roboto Slab|700|||||||&#8221; text_text_color=&#8221;#0d91a2&#8243; text_font_size=&#8221;25px&#8221; header_2_font=&#8221;|600|||||||&#8221; header_2_font_size=&#8221;55px&#8221; text_font_size_tablet=&#8221;25px&#8221; text_font_size_phone=&#8221;20px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; header_2_font_size_tablet=&#8221;65px&#8221; header_2_font_size_phone=&#8221;30px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]\n<p style=\"text-align: center; margin-bottom: 1%;\" class=\"manuscrita\">Estudio Aequus<\/p>\n<h2 style=\"text-align: center;\"><span>Who are we?<\/span><\/h2>\n[\/et_pb_text][et_pb_text _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;|300|||||||&#8221; custom_padding=&#8221;||0px|||&#8221; global_colors_info=&#8221;{}&#8221;]\n<p><a href=\"https:\/\/estudioaequus.com\/en\/\"><br \/>\n  <strong>Aequus Studio<\/strong><br \/>\n<\/a>your specialized Body Health Center in <strong>Palma de Mallorca<\/strong>.<\/p>\n<p>We are specialists in:<\/p>\n<ul>\n<li><a href=\"https:\/\/rgmtherapy.com\/\" target=\"_blank\" rel=\"noopener\" title=\"RGM Therapy\">RGM Therapy<\/a><\/li>\n<li><a href=\"https:\/\/rgmtherapy.com\/rgm-training\/\" target=\"_blank\" rel=\"noopener\" title=\"RGM Training\">RGM Training<\/a> &#8220;much more than pilates&#8221;.<\/li>\n<li><a href=\"https:\/\/rgmtherapy.com\/rgm-physiotherapy\/\" target=\"_blank\" rel=\"noopener\" title=\"RGM Physiotherapy\">RGM Physiotherapy<\/a>: Advanced Physical Therapy<\/li>\n<li><a href=\"https:\/\/estudioaequus.com\/en\/hypopressives-palma-de-mallorca\/\" title=\"Hypopressive gymnastics\">Hypopressive gymnastics<\/a><\/li>\n<li><a href=\"https:\/\/estudioaequus.com\/en\/nutritionist-in-mallorca\/\" target=\"_blank\" rel=\"noopener\" title=\"Nutrition\">Nutrition<\/a><\/li>\n<\/ul>\n<p>Our main objective is health and body functionality. Our physiotherapists and RGM Training + Pilates instructors are a synergic team, with a clear objective: <strong>your wellbeing<\/strong>.<\/p>\n<p>Since 2007, we have understood that these synergies are the foundation of our health.<\/p>\n<p>We carry out a musculoskeletal assessment by the Physiotherapist, to set the guidelines for the RGM Training + Pilates instructor and guarantee a personalized and adapted workout.<\/p>\n[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/estudioaequus.com\/wp-content\/uploads\/2023\/03\/nuestro-compromiso-aequus-estudio.jpg&#8221; alt=&#8221;our commitment aequus estudio&#8221; title_text=&#8221;our commitment aequus estudio&#8221; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;4%||||false|false&#8221; border_radii=&#8221;on|10px|10px|10px|10px&#8221; border_color_all=&#8221;#FFFFFF&#8221; box_shadow_style=&#8221;preset2&#8243; box_shadow_blur=&#8221;40px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; width=&#8221;85%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_gallery gallery_ids=&#8221;27792,27793,27794,27795,27796,27797,27798,27799,27800,27801,27802,27803,27804&#8243; show_title_and_caption=&#8221;off&#8221; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_gallery][et_pb_text _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;|300|||||||&#8221; custom_padding=&#8221;||0px|||&#8221; global_colors_info=&#8221;{}&#8221;]\n<p>We are a different project, where we are committed to <strong>holistic treatment<\/strong>. According to the World Health Organization<strong>(WHO<\/strong>), health is defined as &#8220;a state of complete physical, mental and social well-being and not merely the absence of disease or infirmity&#8221;.<\/p>\n<p>We have <strong>two centers in Palma.<\/strong> One opened in 2007 and the second in 2010, where our specialty is health, through functional training RGM Training + Pilates, with over 180,000 classes of experience.<\/p>\n<p>We have a team integrated by Physical Education graduates, physiotherapists, dancers, instructors, etc. All with a dense training in the &#8220;Pilates&#8221; environment and certified in RGM Training, health and years of experience, with our technical director, Elena Garcia with more than 18 years as a Master in the Pilates Method and specialist in RGM Therapy.<\/p>\n<p>&#8220;Many of the common pathologies with <strong>functional and preventive physical work<\/strong>, would not involve present or future pain.&#8221;<\/p>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; prev_background_color=&#8221;#ffffff&#8221; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#f0f0f0&#8243; top_divider_style=&#8221;wave2&#8243; top_divider_height=&#8221;50px&#8221; top_divider_height_tablet=&#8221;50px&#8221; top_divider_height_phone=&#8221;30px&#8221; top_divider_height_last_edited=&#8221;on|phone&#8221; bottom_divider_style=&#8221;wave2&#8243; bottom_divider_color=&#8221;#FFFFFF&#8221; bottom_divider_height=&#8221;50px&#8221; bottom_divider_flip=&#8221;horizontal&#8221; bottom_divider_height_tablet=&#8221;50px&#8221; bottom_divider_height_phone=&#8221;30px&#8221; bottom_divider_height_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; width=&#8221;85%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Roboto Slab|700|||||||&#8221; text_text_color=&#8221;#0d91a2&#8243; text_font_size=&#8221;25px&#8221; header_2_font=&#8221;|600|||||||&#8221; header_2_font_size=&#8221;55px&#8221; text_font_size_tablet=&#8221;25px&#8221; text_font_size_phone=&#8221;20px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; header_2_font_size_tablet=&#8221;65px&#8221; header_2_font_size_phone=&#8221;30px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]\n<p style=\"text-align: center; margin-bottom: 1%;\" class=\"manuscrita\">Meet<\/p>\n<h2 style=\"text-align: center;\">Our commitment<\/h2>\n[\/et_pb_text][et_pb_text _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;|300|||||||&#8221; custom_padding=&#8221;||0px|||&#8221; global_colors_info=&#8221;{}&#8221;]\n<p>In our Estudio Aequus centers through RGM Therapy + Pilates, therapeutic exercise and physiotherapy &#8220;We are committed to your Body&#8221; and your health, offering you an experience of the highest quality, for the most perfect machine ever created: The Human Body.<\/p>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,2_3&#8243; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; width=&#8221;85%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/estudioaequus.com\/wp-content\/uploads\/2023\/03\/centro-salud-corporal-sobre-nosotros-aequus.jpg&#8221; alt=&#8221;body health center about us aequus&#8221; title_text=&#8221;body health center about us aequus&#8221; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; custom_margin=&#8221;0%||||false|false&#8221; border_radii=&#8221;on|10px|10px|10px|10px&#8221; border_color_all=&#8221;#FFFFFF&#8221; box_shadow_style=&#8221;preset2&#8243; box_shadow_blur=&#8221;40px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;2_3&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;|300|||||||&#8221; custom_padding=&#8221;||0px|||&#8221; global_colors_info=&#8221;{}&#8221;]\n<p>We are the only center that teaches at 8 levels through the educational process of <strong>Rehabilitation, Recovery and Global Re-education in Movement RGM<\/strong>, ranging from Initiation to Advanced level, with synergies between the different professionals, to ensure the highest quality.<\/p>\n<p>We have also acquired another commitment, creating Aequus Mujer, so that at all times, whether due to age or need, she is attended by an adequate and qualified professional.<\/p>\n<p>In our <a href=\"https:\/\/estudioaequus.com\/en\/nutritionist-in-mallorca\/\">physiotherapy center<\/a> we will always advise you with the utmost honesty. We are your Physiotherapy Center and RGM Training: &#8220;Much more than Pilates&#8221;.<\/p>\n<p>We care about you. Therefore, our commitment and objective is not only to prevent, palliate, soften or attenuate the pathology.<\/p>\n<ul>\n<li>We look for and act on the root of the problem<\/li>\n<li>We strive for the full reintegration of the patient-client into his or her daily life.<\/li>\n<li>We help you to mechanize healthy movements<\/li>\n<li>Correct postural hygiene in your day-to-day life<\/li>\n<\/ul>\n<p>Whether for pathology, pain or physical training at the highest level.<\/p>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; width=&#8221;85%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;|300|||||||&#8221; custom_padding=&#8221;||0px|||&#8221; global_colors_info=&#8221;{}&#8221;]\n<p>Let&#8217;s not forget that we have a body and a whole life, and educating and understanding a body is not easy, but with our exclusive system we will achieve it.<\/p>\n<p>Our body is complicated and &#8220;capricious&#8221;, dictating exercises may be easy, however understanding and teaching these bodies to be aware of their movement, generating progressions, adaptations individually and working them with the appropriate means, is a task as complex as the body itself.<\/p>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; background_image=&#8221;https:\/\/estudioaequus.com\/wp-content\/uploads\/2022\/09\/h6-bckr-1.jpeg&#8221; background_size=&#8221;contain&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; width=&#8221;85%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Roboto Slab|700|||||||&#8221; text_text_color=&#8221;#0d91a2&#8243; text_font_size=&#8221;25px&#8221; header_2_font=&#8221;|600|||||||&#8221; header_2_font_size=&#8221;55px&#8221; text_font_size_tablet=&#8221;25px&#8221; text_font_size_phone=&#8221;20px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; header_2_font_size_tablet=&#8221;65px&#8221; header_2_font_size_phone=&#8221;30px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]\n<p style=\"text-align: center; margin-bottom: 1%;\" class=\"manuscrita\">Always at your disposal<\/p>\n<h2 style=\"text-align: center;\"><span>A unique and experienced team<\/span><\/h2>\n[\/et_pb_text][et_pb_text _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;|300|||||||&#8221; custom_padding=&#8221;||0px|||&#8221; global_colors_info=&#8221;{}&#8221;]\n<p align=\"center\" style=\"text-align: center;\"><strong>Personalized attention<\/strong> for each case, a <b>multidisciplinary,<\/b> <strong>professional and experienced<\/strong> team in constant training.<o:p><\/o:p><\/p>\n<p align=\"center\" style=\"text-align: center;\">Specialized in health through movement, thanks to <b>advanced physiotherapy,<\/b> <strong>body awareness<\/strong> and <b>correct posture<\/b>, <b>we will achieve a healthy mind<\/b>.<o:p><\/o:p><\/p>\n[\/et_pb_text][et_pb_video src=&#8221;https:\/\/www.youtube.com\/embed\/zxtRwUCdjn0&#8243; image_src=&#8221;https:\/\/estudioaequus.com\/wp-content\/uploads\/2023\/03\/sobre-nosotros-aequus-video.jpg&#8221; play_icon_color=&#8221;#437ea5&#8243; font_icon=&#8221;&#x49;||divi||400&#8243; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_video][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; width=&#8221;85%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Roboto Slab|700|||||||&#8221; text_text_color=&#8221;#0d91a2&#8243; text_font_size=&#8221;25px&#8221; header_2_font=&#8221;|600|||||||&#8221; header_2_font_size=&#8221;55px&#8221; text_font_size_tablet=&#8221;25px&#8221; text_font_size_phone=&#8221;20px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; header_2_font_size_tablet=&#8221;65px&#8221; header_2_font_size_phone=&#8221;30px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]\n<p style=\"text-align: center; margin-bottom: 1%;\" class=\"manuscrita\">Where we are<\/p>\n<h2 style=\"text-align: center;\">Come and meet us<\/h2>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; width=&#8221;85%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Roboto Slab|700|||||||&#8221; text_text_color=&#8221;#0d91a2&#8243; text_font_size=&#8221;36px&#8221; header_2_font=&#8221;|600|||||||&#8221; header_2_font_size=&#8221;55px&#8221; link_option_url=&#8221;https:\/\/www.google.com\/maps?cid=3298105278751947926&#8243; link_option_url_new_window=&#8221;on&#8221; text_font_size_tablet=&#8221;25px&#8221; text_font_size_phone=&#8221;20px&#8221; text_font_size_last_edited=&#8221;on|desktop&#8221; header_2_font_size_tablet=&#8221;65px&#8221; header_2_font_size_phone=&#8221;30px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]\n<p style=\"text-align: center; margin-bottom: 1%;\" class=\"manuscrita\">Estudio Aequus 1<\/p>\n[\/et_pb_text][et_pb_blurb url=&#8221;https:\/\/www.google.com\/maps?cid=3298105278751947926&#8243; url_new_window=&#8221;on&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xe081;||divi||400&#8243; icon_placement=&#8221;left&#8221; image_icon_width=&#8221;34px&#8221; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]\n<p><a href=\"https:\/\/www.google.com\/maps?cid=3298105278751947926\" target=\"_blank\" rel=\"noopener\">Carrer de Costa Rica 1, 07014 Palma, Illes Balears, Spain<\/a><\/p>\n[\/et_pb_blurb][et_pb_blurb url=&#8221;tel:+34%20971%2028%2068%2038&#8243; url_new_window=&#8221;on&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xf879;||fa||900&#8243; icon_placement=&#8221;left&#8221; image_icon_width=&#8221;34px&#8221; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]\n<p><a href=\"tel:+34%20971%2028%2068%2038\">+34 971 28 68 38<\/a><\/p>\n[\/et_pb_blurb][et_pb_blurb url=&#8221;tel:+34%20673%2091%2032%2024&#8243; url_new_window=&#8221;on&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xe00b;||divi||400&#8243; icon_placement=&#8221;left&#8221; image_icon_width=&#8221;34px&#8221; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]\n<p><a href=\"tel:+34%20673%2091%2032%2024\">+34 673 91 32 24<\/a><\/p>\n[\/et_pb_blurb][et_pb_blurb url=&#8221;mailto:info@estudioaequus.com&#8221; url_new_window=&#8221;on&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xe076;||divi||400&#8243; icon_placement=&#8221;left&#8221; image_icon_width=&#8221;34px&#8221; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]\n<p><a href=\"mailto:info@estudioaequus.com\">info@estudioaequus.com<\/a><\/p>\n[\/et_pb_blurb][et_pb_blurb url=&#8221;mailto:info@estudioaequus.com&#8221; url_new_window=&#8221;on&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xe06b;||divi||400&#8243; icon_placement=&#8221;left&#8221; image_icon_width=&#8221;34px&#8221; _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]Monday to Thursday : 07:30 &#8211; 21.30<br \/>\nFriday : 08:00 &#8211; 19:30 and Saturday : 09:30 &#8211; 13:30[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/estudioaequus.com\/wp-content\/uploads\/2023\/03\/estudio-aequus-1-mapa.jpg&#8221; alt=&#8221;aequus study 1&#8243; title_text=&#8221;aequus study 1&#8243; url=&#8221;https:\/\/www.google.com\/maps?cid=3298105278751947926&#8243; url_new_window=&#8221;on&#8221; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; module_class=&#8221;inverse&#8221; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; width=&#8221;85%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/estudioaequus.com\/wp-content\/uploads\/2023\/03\/estudio-aequus-2-mapa.jpg&#8221; alt=&#8221;aequus study 2&#8243; title_text=&#8221;aequus study 2&#8243; url=&#8221;https:\/\/www.google.com\/maps?cid=15767861066103765285&#8243; url_new_window=&#8221;on&#8221; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Roboto Slab|700|||||||&#8221; text_text_color=&#8221;#0d91a2&#8243; text_font_size=&#8221;36px&#8221; header_2_font=&#8221;|600|||||||&#8221; header_2_font_size=&#8221;55px&#8221; link_option_url=&#8221;https:\/\/www.google.com\/maps?cid=15767861066103765285&#8243; link_option_url_new_window=&#8221;on&#8221; text_font_size_tablet=&#8221;25px&#8221; text_font_size_phone=&#8221;20px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; header_2_font_size_tablet=&#8221;65px&#8221; header_2_font_size_phone=&#8221;30px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]\n<p style=\"text-align: center; margin-bottom: 1%;\" class=\"manuscrita\">Estudio Aequus 2<\/p>\n[\/et_pb_text][et_pb_blurb url=&#8221;https:\/\/www.google.com\/maps?cid=15767861066103765285&#8243; url_new_window=&#8221;on&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xe081;||divi||400&#8243; icon_placement=&#8221;left&#8221; image_icon_width=&#8221;34px&#8221; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]\n<p><a href=\"https:\/\/www.google.com\/maps?cid=15767861066103765285\" target=\"_blank\" rel=\"noopener\">Carrer Vicen\u00e7 Joan i Rossell\u00f3, 32, 07013 Palma, Illes Balears, Spain<\/a><\/p>\n[\/et_pb_blurb][et_pb_blurb url=&#8221;tel:+34%20971%2022%2026%2073&#8243; url_new_window=&#8221;on&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xf879;||fa||900&#8243; icon_placement=&#8221;left&#8221; image_icon_width=&#8221;34px&#8221; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]\n<p><a href=\"tel:+34%20971%2022%2026%2073\">+34 971 22 26 73<\/a><\/p>\n[\/et_pb_blurb][et_pb_blurb url=&#8221;tel:+34%20673%2091%2032%2024&#8243; url_new_window=&#8221;on&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xe00b;||divi||400&#8243; icon_placement=&#8221;left&#8221; image_icon_width=&#8221;34px&#8221; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]\n<p><a href=\"tel:+34%20673%2091%2032%2024\">+34 673 91 32 24<\/a><\/p>\n[\/et_pb_blurb][et_pb_blurb url=&#8221;mailto:info@estudioaequus.com&#8221; url_new_window=&#8221;on&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xe076;||divi||400&#8243; icon_placement=&#8221;left&#8221; image_icon_width=&#8221;34px&#8221; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]\n<p><a href=\"mailto:info@estudioaequus.com\">info@estudioaequus.com<\/a><\/p>\n[\/et_pb_blurb][et_pb_blurb url=&#8221;mailto:info@estudioaequus.com&#8221; url_new_window=&#8221;on&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xe06b;||divi||400&#8243; icon_placement=&#8221;left&#8221; image_icon_width=&#8221;34px&#8221; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]Monday to Friday : 08:30 &#8211; 21.00[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#0d91a2&#8243; background_enable_color=&#8221;off&#8221; custom_margin=&#8221;0%||||false|false&#8221; custom_padding=&#8221;0px||0px|||&#8221; global_module=&#8221;177&#8243; saved_tabs=&#8221;all&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#0e327b&#8221; background_image=&#8221;https:\/\/estudioaequus.com\/wp-content\/uploads\/2022\/09\/client-right-design.png&#8221; background_size=&#8221;initial&#8221; background_position=&#8221;center_right&#8221; background_horizontal_offset=&#8221;-8%&#8221; z_index=&#8221;1&#8243; width_tablet=&#8221;&#8221; width_phone=&#8221;90%&#8221; width_last_edited=&#8221;on|phone&#8221; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;10px||||false|false&#8221; background_last_edited=&#8221;on|phone&#8221; background_enable_image_phone=&#8221;off&#8221; border_radii=&#8221;off|10px|10px||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;|600|||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_font_size=&#8221;50px&#8221; custom_margin=&#8221;2%||||false|false&#8221; text_font_size_tablet=&#8221;50px&#8221; text_font_size_phone=&#8221;30px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]\n<p style=\"text-align: center;\"><span>Book your appointment now!<\/span><\/p>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#0e327b&#8221; background_image=&#8221;https:\/\/estudioaequus.com\/wp-content\/uploads\/2022\/09\/clients-left-design.png&#8221; background_size=&#8221;initial&#8221; background_position=&#8221;center_left&#8221; background_horizontal_offset=&#8221;-8%&#8221; z_index=&#8221;1&#8243; width_tablet=&#8221;&#8221; width_phone=&#8221;90%&#8221; width_last_edited=&#8221;on|phone&#8221; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;5px||||false|false&#8221; background_last_edited=&#8221;on|phone&#8221; background_enable_image_phone=&#8221;off&#8221; border_radii=&#8221;off|||10px|10px&#8221; box_shadow_style=&#8221;preset3&#8243; box_shadow_vertical=&#8221;16px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_button button_url=&#8221;https:\/\/estudioaequus.com\/contacto\/&#8221; button_text=&#8221;MAKE AN APPOINTMENT&#8221; button_alignment=&#8221;center&#8221; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_text_color=&#8221;#0e327b&#8221; button_bg_color=&#8221;#FFFFFF&#8221; button_border_width=&#8221;0px&#8221; button_border_radius=&#8221;10px&#8221; button_font=&#8221;|||on|||||&#8221; button_use_icon=&#8221;off&#8221; custom_margin=&#8221;||||false|false&#8221; custom_padding=&#8221;|50px||50px|false|true&#8221; box_shadow_style=&#8221;preset1&#8243; global_colors_info=&#8221;{}&#8221; button_text_color__hover_enabled=&#8221;on|hover&#8221; button_text_color__hover=&#8221;#FFFFFF&#8221; button_bg_color__hover_enabled=&#8221;on|desktop&#8221; button_bg_color__hover=&#8221;RGBA(255,255,255,0)&#8221; button_bg_enable_color__hover=&#8221;on&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; background_enable_color=&#8221;off&#8221; custom_margin=&#8221;-7%||||false|false&#8221; custom_padding=&#8221;10%||||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; width=&#8221;85%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Roboto Slab|700|||||||&#8221; text_text_color=&#8221;#0d91a2&#8243; text_font_size=&#8221;25px&#8221; header_2_font=&#8221;|600|||||||&#8221; header_2_font_size=&#8221;55px&#8221; text_font_size_tablet=&#8221;25px&#8221; text_font_size_phone=&#8221;20px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; header_2_font_size_tablet=&#8221;65px&#8221; header_2_font_size_phone=&#8221;30px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]\n<p style=\"text-align: center; margin-bottom: 1%;\" class=\"manuscrita\">Professionals<\/p>\n<h2 style=\"text-align: center;\">Your body health specialists in Palma<\/h2>\n[\/et_pb_text][et_pb_text _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;|300|||||||&#8221; global_colors_info=&#8221;{}&#8221;]\n<p>We are specialists in RGM Therapy: Rehabilitation, Recovery and Global Reeducation in Movement, &#8220;much more than Pilates&#8221;, advanced physiotherapy, hypopressive gymnastics, nutrition, personal training with RGM fundamentals, among many other services.<o:p><\/o:p><\/p>\n<p>Our main objective is <b>health <\/b>and <b>body functionality<\/b>. We have a synergic team with a clear objective: your <b>well-being<\/b>.<o:p><\/o:p><\/p>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_4,3_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; width=&#8221;85%&#8221; global_module=&#8221;28202&#8243; saved_tabs=&#8221;all&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|10px|10px|10px|10px&#8221; box_shadow_style=&#8221;preset1&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/estudioaequus.com\/wp-content\/uploads\/2023\/05\/elena-garcia-directora-tecnica-instructora.jpg&#8221; alt=&#8221;fisioterapeuta elena garcia en palma&#8221; title_text=&#8221;elena-garcia-directora-tecnica-instructora&#8221; show_bottom_space=&#8221;off&#8221; _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;off|10px|10px||&#8221; border_color_all=&#8221;#FFFFFF&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_font_size=&#8221;19px&#8221; header_3_font=&#8221;|600|||||||&#8221; header_3_text_color=&#8221;#FFFFFF&#8221; header_3_font_size=&#8221;30px&#8221; background_color=&#8221;#0e327b&#8221; background_enable_image=&#8221;off&#8221; background_size=&#8221;contain&#8221; background_blend=&#8221;multiply&#8221; text_orientation=&#8221;center&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;2%|5%|2%|5%|true|true&#8221; custom_css_main_element=&#8221;||&#8221; global_colors_info=&#8221;{}&#8221;]\n<p style=\"text-align: left;\"><strong>Elena Garc\u00eda Ortiz<\/strong><\/p>\n[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;3_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; border_radii=&#8221;on|5px|5px|5px|5px&#8221; box_shadow_style=&#8221;preset1&#8243; box_shadow_blur=&#8221;10px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;|300|||||||&#8221; custom_padding=&#8221;2%|5%|2%|5%|true|true&#8221; custom_padding_tablet=&#8221;&#8221; custom_padding_phone=&#8221;5%||5%||true|true&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]\n<p><b>Technical Director and Instructor<\/b><\/p>\n<ul>\n<li><span>Degree in Physical Education INEF from the University of Lleida.<\/span><\/li>\n<li><span>Master in aerobics<\/span><\/li>\n<li><span>Master in Fitness<\/span><\/li>\n<li><span>Master&#8217;s Degree in Rhythmic and Sports Gymnastics<\/span><\/li>\n<li><span>Pilates Movement: Levels from Basic to Super Advanced, from Floor and Machines. hip, joints, cervical, etc&#8230;<\/span><\/li>\n<li><span>Stott Pilates: 32 hours<\/span><\/li>\n<li><span>PoleStar Pilates: 1 year to become a Pilates teacher<\/span><\/li>\n<li><span>Peak Pilates: 36 hours<\/span><\/li>\n<li><span>BTS Body Balance and Body Pump Instructor, updated training courses<\/span><\/li>\n<li><span>Toning, Step and Aerobic Fitness Pentathlon<\/span><\/li>\n<li><span>Indoor cycling and Tot Cycling instructor (Spinning, taught by Kim Forteza).<\/span> <\/li>\n<span class=\"collapseomatic \" id=\"id6a0489689a9c6\"  tabindex=\"0\" title=\"Leer m\u00e1s\"    >Leer m\u00e1s<\/span><div id=\"target-id6a0489689a9c6\" class=\"collapseomatic_content \">\n<li><span>Stretching<\/span><\/li>\n<li><span>Pilates Movement Training Course: Basic to Super Advanced Levels, Floor and Machine.<\/span><\/li>\n<li><span>Complementary courses of Pilates Movement Training with Hoops, Balance Board, Balls, Elastic Bands, Small Arch, Spine Corrector.<\/span><\/li>\n<li><span>Torres I and II Pilates Movement Workshop.<\/span><\/li>\n<li><span>Complementary Pilates Movement Training Scoliosis course.<\/span><\/li>\n<li><span>Course Recovery of pathologies with Pilates material, Shoulder and Hip. Pilatescenter Conxi Mart\u00ed.<\/span><\/li>\n<li><span>Pilates &amp; Suspension workshop given by Karol Tamayo.<\/span><\/li>\n<li><span>Pilates Teacher Training Seminar, Jumpboard, Magic Circle, Power Reformer, taught by Karol Tamayo, Evolution Academy.<\/span><\/li>\n<li><span>Open Your Back course, given by the international Pilates Evidence School.<\/span><\/li>\n<li><span>Biomechanics &amp; Clinical Reformer, course taught by Isaac Fernandez, Xtensal, Biomechanics applied to the Pilates Method.<\/span><\/li>\n<li><span>TRX Suspension Training Course.<\/span><\/li>\n<li><span>A Week of Classical Pilates, Gratz Guillotine, Reformer, Mat, Cadillac, Chairs, Barrels, taught by MeJo Wiggin.<\/span><\/li>\n<li><span>Specialization courses with XTensa by Isaac Hernandez:<\/span><\/li>\n<li><span>Scoliosis specialization seminar.<\/span><\/li>\n<li><span>Course on understanding pain and progressive reformer.<\/span><\/li>\n<li><span>Hip-Knee-Ankle specialization course.<\/span><\/li>\n<li><span>Pilates Method pregnancy Floor and Machines.<\/span><\/li>\n<li><span>Biomechanics and Clinical Reformer Course<\/span><\/li>\n<li><span>Pilates Method and Herniated Disc Course.<\/span><\/li>\n<li><span>+ More than 23 years of training and nearly 25,000 hours of classes taught working from hygiene and mechanization of posture with people with all kinds of musculoskeletal needs such as hernias, prostheses, scoliosis, kyphosis, etc.. Specialized in functional, compensatory and educational training focused on pain and pathology.<\/span><\/li>\n<\/ul>\n<\/div>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_4,3_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; width=&#8221;85%&#8221; global_module=&#8221;28204&#8243; saved_tabs=&#8221;all&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|10px|10px|10px|10px&#8221; box_shadow_style=&#8221;preset1&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/estudioaequus.com\/wp-content\/uploads\/2023\/03\/guillermo-homar-ferrer.jpeg&#8221; alt=&#8221;Guillermo Homar Ferrer&#8221; title_text=&#8221;Guillermo Homar Ferrer&#8221; show_bottom_space=&#8221;off&#8221; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;off|10px|10px||&#8221; border_color_all=&#8221;#FFFFFF&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_font_size=&#8221;19px&#8221; header_3_font=&#8221;|600|||||||&#8221; header_3_text_color=&#8221;#FFFFFF&#8221; header_3_font_size=&#8221;30px&#8221; background_color=&#8221;#0e327b&#8221; background_enable_image=&#8221;off&#8221; background_size=&#8221;contain&#8221; background_blend=&#8221;multiply&#8221; text_orientation=&#8221;center&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;2%|5%|2%|5%|true|true&#8221; custom_css_main_element=&#8221;||&#8221; global_colors_info=&#8221;{}&#8221;]\n<p style=\"text-align: left;\"><strong>Guillermo Homar Ferrer<\/strong><\/p>\n[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;3_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; border_radii=&#8221;on|5px|5px|5px|5px&#8221; box_shadow_style=&#8221;preset1&#8243; box_shadow_blur=&#8221;10px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;|300|||||||&#8221; custom_padding=&#8221;2%|5%|2%|5%|true|true&#8221; custom_padding_tablet=&#8221;&#8221; custom_padding_phone=&#8221;5%||5%||true|true&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<b>Manager &#8211; Founding Partner<\/b><\/p>\n<ul>\n<li aria-level=\"1\"><span>Accountant of Metalnox,S.L<\/span><\/li>\n<li aria-level=\"1\"><span>Deputy Director of Boulevar Universitario<\/span><\/li>\n<li aria-level=\"1\"><span>Osborne sales representative<\/span><\/li>\n<li aria-level=\"1\"><span>Manager and owner of Vuelos Balear,S.L.<\/span><\/li>\n<li aria-level=\"1\"><span>Manager of Aluminplast,S.L. and Prevefoc Insular,S.L.<\/span><\/li>\n<li aria-level=\"1\"><span>Sales representative for Sensormatic and Azimut Group<\/span><\/li>\n<\/ul>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_4,3_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; width=&#8221;85%&#8221; global_module=&#8221;28243&#8243; saved_tabs=&#8221;all&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|10px|10px|10px|10px&#8221; box_shadow_style=&#8221;preset1&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/estudioaequus.com\/wp-content\/uploads\/2023\/05\/instructora-rgm-elisa-caminals.jpg&#8221; alt=&#8221;Guillermo Homar Ferrer&#8221; title_text=&#8221;instructora-rgm-elisa-caminals&#8221; show_bottom_space=&#8221;off&#8221; _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;off|10px|10px||&#8221; border_color_all=&#8221;#FFFFFF&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_font_size=&#8221;19px&#8221; header_3_font=&#8221;|600|||||||&#8221; header_3_text_color=&#8221;#FFFFFF&#8221; header_3_font_size=&#8221;30px&#8221; background_color=&#8221;#0e327b&#8221; background_enable_image=&#8221;off&#8221; background_size=&#8221;contain&#8221; background_blend=&#8221;multiply&#8221; text_orientation=&#8221;center&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;2%|5%|2%|5%|true|true&#8221; custom_css_main_element=&#8221;||&#8221; global_colors_info=&#8221;{}&#8221;]\n<p style=\"text-align: left;\"><strong>Elisa Caminals<\/strong><\/p>\n[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;3_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; border_radii=&#8221;on|5px|5px|5px|5px&#8221; box_shadow_style=&#8221;preset1&#8243; box_shadow_blur=&#8221;10px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;|300|||||||&#8221; custom_padding=&#8221;2%|5%|2%|5%|true|true&#8221; custom_padding_tablet=&#8221;&#8221; custom_padding_phone=&#8221;5%||5%||true|true&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<b>RGM Instructor<\/b><\/p>\n<ul>\n<li><span>Pilates Movement Training Course: Basic to Super Advanced Levels, Floor and Machine.<\/span><\/li>\n<li><span>Complementary courses of Pilates Movement Training with Hoops, Balance Board, Balls, Elastic Bands, Small Arch, Spine Corrector.<\/span><\/li>\n<li><span>Torres I and II Pilates Movement Workshop.<\/span><\/li>\n<li><span>Complementary Pilates Movement Training Scoliosis course.<\/span><\/li>\n<li><span>Participation in the Stott Pilates Essential to Intermediate Matwork workshop.<\/span><\/li>\n<li><span>Advanced Biomechanics and Clinical Reformer Workshop, taught by Isaac Mu\u00f1oz, National Pilates Certification Program.<\/span><\/li>\n<li><span>Pilates Workshop on Studio Machines, taught by Rocio Carceles, Peak Pilates Spain.<\/span><\/li>\n<li><span>Course Recovery of pathologies with Pilates material, Shoulder and Hip. Pilatescenter Conxi Mart\u00ed.<\/span><\/li>\n<li><span>Pilates &amp; Suspension workshop given by Karol Tamayo.<\/span><\/li>\n<li><span>Pilates Teacher Training Seminar, Jumpboard, Magic Circle, Power Reformer, taught by Karol Tamayo, Evolution Academy.<\/span><\/li>\n<li><span>Open Your Back course, given by the international Pilates Evidence School.<\/span><\/li>\n<span class=\"collapseomatic \" id=\"id6a0489689aa7b\"  tabindex=\"0\" title=\"Leer m\u00e1s\"    >Leer m\u00e1s<\/span><div id=\"target-id6a0489689aa7b\" class=\"collapseomatic_content \">\n<li><span>Workshop Introduction to the Bowspring , given by Desi Springer and John Friend.<\/span><\/li>\n<li><span>First responder in mountain accidents workshop given by SOSMONTA\u00d1A.<\/span><\/li>\n<li><span>Biomechanics &amp; Clinical Reformer, course taught by Isaac Fernandez, Xtensal<\/span><\/li>\n<li><span>Biomechanics applied to the Pilates Method.<\/span><\/li>\n<li><span>Pilates Floor Workshop, given by F.E.D.A (Spanish Federation of Aerobics and Fitness).<\/span><\/li>\n<li><span>TRX Suspension Training Course.<\/span><\/li>\n<li><span>A Week of Classical Pilates, Gratz Guillotine, Reformer, Mat, Cadillac, Chairs, Barrels, taught by MeJo Wiggin.<\/span><\/li>\n<\/ul>\n<\/div>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_4,3_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; width=&#8221;85%&#8221; global_module=&#8221;28282&#8243; saved_tabs=&#8221;all&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|10px|10px|10px|10px&#8221; box_shadow_style=&#8221;preset1&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/estudioaequus.com\/wp-content\/uploads\/2023\/05\/instructora-rgm-paloma-otero.jpg&#8221; alt=&#8221;Guillermo Homar Ferrer&#8221; title_text=&#8221;instructora-rgm-paloma-otero&#8221; show_bottom_space=&#8221;off&#8221; _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;off|10px|10px||&#8221; border_color_all=&#8221;#FFFFFF&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_font_size=&#8221;19px&#8221; header_3_font=&#8221;|600|||||||&#8221; header_3_text_color=&#8221;#FFFFFF&#8221; header_3_font_size=&#8221;30px&#8221; background_color=&#8221;#0e327b&#8221; background_enable_image=&#8221;off&#8221; background_size=&#8221;contain&#8221; background_blend=&#8221;multiply&#8221; text_orientation=&#8221;center&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;2%|5%|2%|5%|true|true&#8221; custom_css_main_element=&#8221;||&#8221; global_colors_info=&#8221;{}&#8221;]\n<p style=\"text-align: left;\"><strong>Paloma Otero<\/strong><\/p>\n[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;3_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; border_radii=&#8221;on|5px|5px|5px|5px&#8221; box_shadow_style=&#8221;preset1&#8243; box_shadow_blur=&#8221;10px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;|300|||||||&#8221; custom_padding=&#8221;2%|5%|2%|5%|true|true&#8221; custom_padding_tablet=&#8221;&#8221; custom_padding_phone=&#8221;5%||5%||true|true&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<b>RGM Instructor<\/b><\/p>\n<ul>\n<li><span>Pilates Reformer and Pilates Mat Instructor<\/span><\/li>\n<li><span>Pilates Reformer and Pilates Mat Instructor at CEAF Institute, Argentina. With Virginia LoVotrico and Gustavo Muller.<\/span><\/li>\n<li><span>Training in biomechanics and anatomy at CEAF Institute, Argentina. With Gustavo Muller.<\/span><\/li>\n<li><span>First Aid, nutrition and emotional intelligence training at CEAF Institute. With Gustavo Muller.<\/span><\/li>\n<\/ul>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_4,3_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; width=&#8221;85%&#8221; global_module=&#8221;28246&#8243; saved_tabs=&#8221;all&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|10px|10px|10px|10px&#8221; box_shadow_style=&#8221;preset1&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/estudioaequus.com\/wp-content\/uploads\/2023\/05\/instructora-rgm-vicente-rosello.jpg&#8221; alt=&#8221;Guillermo Homar Ferrer&#8221; title_text=&#8221;instructora-rgm-vicente-rosello&#8221; show_bottom_space=&#8221;off&#8221; _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;off|10px|10px||&#8221; border_color_all=&#8221;#FFFFFF&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_font_size=&#8221;19px&#8221; header_3_font=&#8221;|600|||||||&#8221; header_3_text_color=&#8221;#FFFFFF&#8221; header_3_font_size=&#8221;30px&#8221; background_color=&#8221;#0e327b&#8221; background_enable_image=&#8221;off&#8221; background_size=&#8221;contain&#8221; background_blend=&#8221;multiply&#8221; text_orientation=&#8221;center&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;2%|5%|2%|5%|true|true&#8221; custom_css_main_element=&#8221;||&#8221; global_colors_info=&#8221;{}&#8221;]\n<p style=\"text-align: left;\"><strong>Vicente Rosello<\/strong><\/p>\n[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;3_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; border_radii=&#8221;on|5px|5px|5px|5px&#8221; box_shadow_style=&#8221;preset1&#8243; box_shadow_blur=&#8221;10px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;|300|||||||&#8221; custom_padding=&#8221;2%|5%|2%|5%|true|true&#8221; custom_padding_tablet=&#8221;&#8221; custom_padding_phone=&#8221;5%||5%||true|true&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<b>RGM Instructor<\/b><\/p>\n<ul>\n<li><span>Original Pilates Method, Pilates Rotterdam, 2021-2022<\/span><\/li>\n<li><span>Open your back workshop, E.I. Pilates Evidence, 2021<\/span><\/li>\n<li><span>Pilates &amp; Suspension Workshop, Evolution Academy, 2019<\/span><\/li>\n<li><span>Pilates Teacher Training Seminar, Evolution Academy, 2019<\/span><\/li>\n<li><span>Sports Facilities Manager, Apta Vital Sport, 2015<\/span><\/li>\n<li><span>Creator of Total Relaxation Workshop, Relaxation sessions, Stretching and Psychosomatic Integral Training. 2013<\/span><\/li>\n<li><span>Pilates Method Teacher Basic, Intermediate and Advanced level, Matt and Studio (Reformer, Cadillac, Tower, Wunda, High Chair, Ladder Barrel). Pilates Movement School. 2006-2012.<\/span><\/li>\n<li><span>Complementary courses of the M.P. with implements: Elastic Band, Fittball and Softball, Balance Board, Foam Roller, Power Circle, Baby Arc, Spine Corrector, and for special cases: Pregnant women, Scoliosis, Senior Citizens. Pilates Movement School. 2006-2012.<\/span><\/li>\n<span class=\"collapseomatic \" id=\"id6a0489689aaf9\"  tabindex=\"0\" title=\"Leer m\u00e1s\"    >Leer m\u00e1s<\/span><div id=\"target-id6a0489689aaf9\" class=\"collapseomatic_content \">\n<li><span>Fitness Era Convention, seminars: &#8220;Assessing Pilates Client Needs&#8221;; &#8220;Programming and Retaining Pilates Clients&#8221;; &#8220;Enjoy Pilates&#8221; and &#8220;Breathing and Center Connection&#8221;. Orthos Training and Health, Sant Cugat del Valles. 2006<\/span><\/li>\n<li><span>Chi Kung Master, Tan Tien School 2012<\/span><\/li>\n<li><span>Seminar &#8220;Effective Communication in Learning Processes&#8221;. Tan Tien School. 2012<\/span><\/li>\n<li><span>Self-taught in Total Relaxation (CNS and VNS) and Stretching.<\/span><\/li>\n<\/ul>\n<\/div>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_4,3_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; width=&#8221;85%&#8221; global_module=&#8221;28247&#8243; saved_tabs=&#8221;all&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|10px|10px|10px|10px&#8221; box_shadow_style=&#8221;preset1&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/estudioaequus.com\/wp-content\/uploads\/2023\/05\/instructora-maria-jose-sosa.jpeg&#8221; alt=&#8221;Guillermo Homar Ferrer&#8221; title_text=&#8221;instructora-maria-jose-sosa&#8221; show_bottom_space=&#8221;off&#8221; _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;off|10px|10px||&#8221; border_color_all=&#8221;#FFFFFF&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_font_size=&#8221;19px&#8221; header_3_font=&#8221;|600|||||||&#8221; header_3_text_color=&#8221;#FFFFFF&#8221; header_3_font_size=&#8221;30px&#8221; background_color=&#8221;#0e327b&#8221; background_enable_image=&#8221;off&#8221; background_size=&#8221;contain&#8221; background_blend=&#8221;multiply&#8221; text_orientation=&#8221;center&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;2%|5%|2%|5%|true|true&#8221; custom_css_main_element=&#8221;||&#8221; global_colors_info=&#8221;{}&#8221;]\n<p style=\"text-align: left;\"><strong>Mar\u00eda Jos\u00e9 Sosa<\/strong><\/p>\n[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;3_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; border_radii=&#8221;on|5px|5px|5px|5px&#8221; box_shadow_style=&#8221;preset1&#8243; box_shadow_blur=&#8221;10px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;|300|||||||&#8221; custom_padding=&#8221;2%|5%|2%|5%|true|true&#8221; custom_padding_tablet=&#8221;&#8221; custom_padding_phone=&#8221;5%||5%||true|true&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<b>Instructor<\/b><\/p>\n<ul>\n<li><span>Pilates Mat Training, Personal Pilates, UY, 2013 Pilates in Pregnancy, Personal Pilates, UY, 2014 Reformer, UY, 2014<\/span><\/li>\n<li><span>Rehabilitation and injury prevention, UY, 2016-2017 Specialization in ankle &#8211; knee &#8211; hip, ES 2022.<\/span><\/li>\n<li><span>Currently undergoing a new Pilates Mat &amp; Studio training with Isaac Hernandez&#8217;s XTensal, 2022-2023.<\/span><\/li>\n<\/ul>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_4,3_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; width=&#8221;85%&#8221; global_module=&#8221;28248&#8243; saved_tabs=&#8221;all&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|10px|10px|10px|10px&#8221; box_shadow_style=&#8221;preset1&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/estudioaequus.com\/wp-content\/uploads\/2023\/05\/fisioterapeuta-ivett-arroyo.jpg&#8221; alt=&#8221;Guillermo Homar Ferrer&#8221; title_text=&#8221;fisioterapeuta-ivett-arroyo&#8221; show_bottom_space=&#8221;off&#8221; _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;off|10px|10px||&#8221; border_color_all=&#8221;#FFFFFF&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_font_size=&#8221;19px&#8221; header_3_font=&#8221;|600|||||||&#8221; header_3_text_color=&#8221;#FFFFFF&#8221; header_3_font_size=&#8221;30px&#8221; background_color=&#8221;#0e327b&#8221; background_enable_image=&#8221;off&#8221; background_size=&#8221;contain&#8221; background_blend=&#8221;multiply&#8221; text_orientation=&#8221;center&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;2%|5%|2%|5%|true|true&#8221; custom_css_main_element=&#8221;||&#8221; global_colors_info=&#8221;{}&#8221;]\n<p style=\"text-align: left;\"><strong>Ivett Arroyo<\/strong><\/p>\n[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;3_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; border_radii=&#8221;on|5px|5px|5px|5px&#8221; box_shadow_style=&#8221;preset1&#8243; box_shadow_blur=&#8221;10px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;|300|||||||&#8221; custom_padding=&#8221;2%|5%|2%|5%|true|true&#8221; custom_padding_tablet=&#8221;&#8221; custom_padding_phone=&#8221;5%||5%||true|true&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]\n<p><b>Registered physiotherapist n\u00ba229<\/b><\/p>\n<ul>\n<li><span>Physiotherapist graduated from the Metropolitan University in Barranquilla-Colombia in 1996 and approved for the Spanish title in 2001.<\/span><\/li>\n<\/ul>\n<p><span>Specialist in:<\/span><\/p>\n<ul>\n<li><span>Dermatofunctional or Physioaesthetic Physiotherapy.<\/span><\/li>\n<li><span>Manual therapy<\/span><\/li>\n<li><span>Skeletal muscle injuries.<\/span><\/li>\n<\/ul>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_4,3_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; width=&#8221;85%&#8221; global_module=&#8221;28249&#8243; saved_tabs=&#8221;all&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|10px|10px|10px|10px&#8221; box_shadow_style=&#8221;preset1&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/estudioaequus.com\/wp-content\/uploads\/2023\/05\/fisioterapeuta-miki-mendibar.jpg&#8221; alt=&#8221;Guillermo Homar Ferrer&#8221; title_text=&#8221;physiotherapist-miki-mendibar&#8221; show_bottom_space=&#8221;off&#8221; _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;off|10px|10px||&#8221; border_color_all=&#8221;#FFFFFF&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_font_size=&#8221;19px&#8221; header_3_font=&#8221;|600|||||||&#8221; header_3_text_color=&#8221;#FFFFFF&#8221; header_3_font_size=&#8221;30px&#8221; background_color=&#8221;#0e327b&#8221; background_enable_image=&#8221;off&#8221; background_size=&#8221;contain&#8221; background_blend=&#8221;multiply&#8221; text_orientation=&#8221;center&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;2%|5%|2%|5%|true|true&#8221; custom_css_main_element=&#8221;||&#8221; global_colors_info=&#8221;{}&#8221;]\n<p style=\"text-align: left;\"><strong>Miki Mendibar<\/strong><\/p>\n[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;3_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; border_radii=&#8221;on|5px|5px|5px|5px&#8221; box_shadow_style=&#8221;preset1&#8243; box_shadow_blur=&#8221;10px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.22.1&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;|300|||||||&#8221; custom_padding=&#8221;2%|5%|2%|5%|true|true&#8221; custom_padding_tablet=&#8221;&#8221; custom_padding_phone=&#8221;5%||5%||true|true&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]\n<p><b>Registered Physiotherapist n\u00ba2019<\/b><\/p>\n<ul>\n<li><span>Degree in Physiotherapy (UIB)<\/span><\/li>\n<li><span>Dry needling and electropuncture training (FisioForm Courses)<\/span><\/li>\n<li><span>Specialist Training in Invasive Physiotherapy and Musculoskeletal Ultrasound (FisioForm Courses)<\/span><\/li>\n<li><span>Training in Bases and Principles of Therapeutic Exercise (UCLM)<\/span><\/li>\n<li><span>Training in Ultrasound as an assessment and biofeedback tool (UCLM)<\/span><\/li>\n<li><span>Training in Updating of knowledge in physiotherapy in shoulder soft tissue pathology (UCLM)<\/span><\/li>\n<li><span>Training in Updating of knowledge in physiotherapy in the main musculoskeletal injuries and their complications (UCLM)<\/span><\/li>\n<li><span>Training in Updating knowledge in physiotherapy in ankle injuries (UCLM)<\/span><\/li>\n<\/ul>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_4,3_4&#8243; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; width=&#8221;85%&#8221; global_module=&#8221;28251&#8243; saved_tabs=&#8221;all&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|10px|10px|10px|10px&#8221; box_shadow_style=&#8221;preset1&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/estudioaequus.com\/wp-content\/uploads\/2023\/05\/fisioterapeuta-alvaro-palomino.jpg&#8221; alt=&#8221;Guillermo Homar Ferrer&#8221; title_text=&#8221;fisioterapeuta-alvaro-palomino&#8221; show_bottom_space=&#8221;off&#8221; _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;off|10px|10px||&#8221; border_color_all=&#8221;#FFFFFF&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_font_size=&#8221;19px&#8221; header_3_font=&#8221;|600|||||||&#8221; header_3_text_color=&#8221;#FFFFFF&#8221; header_3_font_size=&#8221;30px&#8221; background_color=&#8221;#0e327b&#8221; background_enable_image=&#8221;off&#8221; background_size=&#8221;contain&#8221; background_blend=&#8221;multiply&#8221; text_orientation=&#8221;center&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;2%|5%|2%|5%|true|true&#8221; custom_css_main_element=&#8221;||&#8221; global_colors_info=&#8221;{}&#8221;]\n<p style=\"text-align: left;\"><strong>Alvaro Palomino<\/strong><\/p>\n[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;3_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; border_radii=&#8221;on|5px|5px|5px|5px&#8221; box_shadow_style=&#8221;preset1&#8243; box_shadow_blur=&#8221;10px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;|300|||||||&#8221; custom_padding=&#8221;2%|5%|2%|5%|true|true&#8221; custom_padding_tablet=&#8221;&#8221; custom_padding_phone=&#8221;5%||5%||true|true&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]\n<p><b>Registered physiotherapist n\u00ba1832<\/b><\/p>\n<ul>\n<li><span>Physiotherapist graduated from the University of Nebrija.<\/span><\/li>\n<li><span>Expert in Manual Therapy by the European University of Madrid.<\/span><\/li>\n<li><span>Degree in Treatment of Mandibular Dysfunctions from the European University of Madrid.<\/span><\/li>\n<li><span>Qualified in Pilates Method by the University School of Physiotherapy of the ONCE.<\/span><\/li>\n<li><span>Qualified in Pilates during pregnancy and postpartum, and Hypopressive Exercises by the Spanish Association of Expert Physiotherapists in Pilates.<\/span><\/li>\n<li><span>Expert in Non Invasive Neuromodulation NESA XSIGNAL.<\/span><\/li>\n<li><span>Qualified in INDIBA ACTIVE THERAPY.<\/span><\/li>\n<\/ul>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_4,3_4&#8243; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; width=&#8221;85%&#8221; global_module=&#8221;28252&#8243; saved_tabs=&#8221;all&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|10px|10px|10px|10px&#8221; box_shadow_style=&#8221;preset1&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/estudioaequus.com\/wp-content\/uploads\/2023\/05\/fisioterapeuta-silvia-ortiz.jpg&#8221; alt=&#8221;Guillermo Homar Ferrer&#8221; title_text=&#8221;fisioterapeuta-silvia-ortiz&#8221; show_bottom_space=&#8221;off&#8221; _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;off|10px|10px||&#8221; border_color_all=&#8221;#FFFFFF&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_font_size=&#8221;19px&#8221; header_3_font=&#8221;|600|||||||&#8221; header_3_text_color=&#8221;#FFFFFF&#8221; header_3_font_size=&#8221;30px&#8221; background_color=&#8221;#0e327b&#8221; background_enable_image=&#8221;off&#8221; background_size=&#8221;contain&#8221; background_blend=&#8221;multiply&#8221; text_orientation=&#8221;center&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;2%|5%|2%|5%|true|true&#8221; custom_css_main_element=&#8221;||&#8221; global_colors_info=&#8221;{}&#8221;]\n<p style=\"text-align: left;\"><strong>Silvia Ortiz<\/strong><\/p>\n[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;3_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; border_radii=&#8221;on|5px|5px|5px|5px&#8221; box_shadow_style=&#8221;preset1&#8243; box_shadow_blur=&#8221;10px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;|300|||||||&#8221; custom_padding=&#8221;2%|5%|2%|5%|true|true&#8221; custom_padding_tablet=&#8221;&#8221; custom_padding_phone=&#8221;5%||5%||true|true&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]\n<p><b>Registered physiotherapis n\u00ba1780<\/b><\/p>\n<ul>\n<li><span>Graduated in Physiotherapy at the Central University of Catalonia.<\/span><\/li>\n<li><span>Specialized in pelvic floor, urogenicology and obstetrics.<\/span><\/li>\n<li><span>Hypopressive Gymnastics Training with Marcel Caufriez<\/span><\/li>\n<li><span>Specialist in Pilates floor and machine Pilates Method with Nature Pilates<\/span><\/li>\n<\/ul>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_4,3_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; width=&#8221;85%&#8221; global_module=&#8221;248652&#8243; saved_tabs=&#8221;all&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|10px|10px|10px|10px&#8221; box_shadow_style=&#8221;preset1&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/estudioaequus.com\/wp-content\/uploads\/2024\/01\/instructora-rgm-caterina.jpg&#8221; alt=&#8221;rgm caterina instructor&#8221; title_text=&#8221;instructor-rgm-caterina&#8221; show_bottom_space=&#8221;off&#8221; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;off|10px|10px||&#8221; border_color_all=&#8221;#FFFFFF&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_font_size=&#8221;19px&#8221; header_3_font=&#8221;|600|||||||&#8221; header_3_text_color=&#8221;#FFFFFF&#8221; header_3_font_size=&#8221;30px&#8221; background_color=&#8221;#0e327b&#8221; background_enable_image=&#8221;off&#8221; background_size=&#8221;contain&#8221; background_blend=&#8221;multiply&#8221; text_orientation=&#8221;center&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;2%|5%|2%|5%|true|true&#8221; custom_css_main_element=&#8221;||&#8221; global_colors_info=&#8221;{}&#8221;]\n<p style=\"text-align: left;\"><strong>Caterina<\/strong><\/p>\n[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;3_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; border_radii=&#8221;on|5px|5px|5px|5px&#8221; box_shadow_style=&#8221;preset1&#8243; box_shadow_blur=&#8221;10px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;|300|||||||&#8221; custom_padding=&#8221;2%|5%|2%|5%|true|true&#8221; custom_padding_tablet=&#8221;&#8221; custom_padding_phone=&#8221;5%||5%||true|true&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]\n<p><b>Registered Physiotherapist n\u00ba2094<\/b><\/p>\n<ul>\n<li><span>Graduated in Physiotherapy at the University of the Balearic Islands.  <\/span><\/li>\n<li><span>Master&#8217;s Degree in the Integral Approach to the Female and Male Pelvic Floor at the European University of Madrid.  <\/span><\/li>\n<li><span>Certification in Pregnancy and Postpartum Training with OWA.<\/span><\/li>\n<li><span>Pessary training with Fisinergia.  <\/span><\/li>\n<li><span>Superior Technician in Physical and Sports Activities Animation.<\/span><\/li>\n<li><span>Training in wood therapy with Silvia L\u00f3pez.<\/span><\/li>\n<\/ul>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_4,3_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; width=&#8221;85%&#8221; saved_tabs=&#8221;all&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|10px|10px|10px|10px&#8221; box_shadow_style=&#8221;preset1&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/estudioaequus.com\/wp-content\/uploads\/2024\/01\/nutricionista-aitana-espinosa.jpg&#8221; alt=&#8221;nutritionist Aitana espinosa&#8221; title_text=&#8221;nutritionist Aitana espinosa&#8221; show_bottom_space=&#8221;off&#8221; _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; hover_enabled=&#8221;0&#8243; border_radii=&#8221;off|10px|10px||&#8221; border_color_all=&#8221;#FFFFFF&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_image][et_pb_text _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_font_size=&#8221;19px&#8221; header_3_font=&#8221;|600|||||||&#8221; header_3_text_color=&#8221;#FFFFFF&#8221; header_3_font_size=&#8221;30px&#8221; background_color=&#8221;#0e327b&#8221; background_enable_image=&#8221;off&#8221; background_size=&#8221;contain&#8221; background_blend=&#8221;multiply&#8221; text_orientation=&#8221;center&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;2%|5%|2%|5%|true|true&#8221; hover_enabled=&#8221;0&#8243; custom_css_main_element=&#8221;||&#8221; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]\n<p style=\"text-align: left;\"><strong>Aitana Espinosa<\/strong><\/p>\n[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;3_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; border_radii=&#8221;on|5px|5px|5px|5px&#8221; box_shadow_style=&#8221;preset1&#8243; box_shadow_blur=&#8221;10px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.23.4&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;|300|||||||&#8221; custom_padding=&#8221;2%|5%|2%|5%|true|true&#8221; custom_padding_tablet=&#8221;&#8221; custom_padding_phone=&#8221;5%||5%||true|true&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; sticky_enabled=&#8221;0&#8243;]<b>Registered Nutritionist No. IB00322<\/b><\/p>\n<ul>\n<li><span>Graduate in human nutrition and dietetics from the University of the Basque Country.<\/span><\/li>\n<li><span>Master in Nutrigenomics and Personalized Nutrition by the University of the Balearic Islands.<\/span><\/li>\n<li><span>Expert Course on Eating Disorders (CEAN)<\/span><\/li>\n<li><span>Attending Expert Course in Digestive Pathologies (CEAN)<\/span><\/li>\n<li><span>Pilates instructor (Deusto Salud)<\/span><\/li>\n<li><span>Personal trainer of high performance and advanced techniques in bodybuilding (APTAVS)<\/span><\/li>\n<\/ul>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.21.0&#8243; _module_preset=&#8221;default&#8221; background_enable_color=&#8221;off&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_stops=&#8221;#ffffff 0%|rgba(0,0,0,0.3) 100%&#8221; background_color_gradient_overlays_image=&#8221;on&#8221; background_image=&#8221;https:\/\/estudioaequus.com\/wp-content\/uploads\/2023\/03\/fisioterapeuta-haciendo-masaje-espalda.jpg&#8221; parallax=&#8221;on&#8221; background_blend=&#8221;multiply&#8221; top_divider_style=&#8221;slant&#8221; top_divider_color=&#8221;#FFFFFF&#8221; top_divider_height=&#8221;50px&#8221; top_divider_flip=&#8221;horizontal&#8221; top_divider_height_tablet=&#8221;50px&#8221; top_divider_height_phone=&#8221;30px&#8221; top_divider_height_last_edited=&#8221;on|phone&#8221; bottom_divider_style=&#8221;slant&#8221; bottom_divider_color=&#8221;RGBA(255,255,255,0)&#8221; bottom_divider_height=&#8221;50px&#8221; bottom_divider_flip=&#8221;horizontal&#8221; bottom_divider_height_tablet=&#8221;50px&#8221; bottom_divider_height_phone=&#8221;30px&#8221; bottom_divider_height_last_edited=&#8221;on|phone&#8221; saved_tabs=&#8221;all&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Roboto Slab||||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_font_size=&#8221;25px&#8221; header_2_font=&#8221;|600|||||||&#8221; header_2_text_color=&#8221;#FFFFFF&#8221; header_2_font_size=&#8221;55px&#8221; text_font_size_tablet=&#8221;25px&#8221; text_font_size_phone=&#8221;20px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; header_2_font_size_tablet=&#8221;65px&#8221; header_2_font_size_phone=&#8221;30px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; text_text_shadow_style=&#8221;preset3&#8243; global_colors_info=&#8221;{}&#8221;]\n<p style=\"text-align: center; margin-bottom: 1%;\">We listen to you<\/p>\n<h2 style=\"text-align: center;\">What our patients say about Estudio Aequus<\/h2>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;0px|||||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]        <div class=\"rplg\" style=\"\" data-id=\"35\"><div class=\"rplg-slider rplg-dark\"><div class=\"rplgsw-container\"><div class=\"rplgsw-wrapper\"><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        La atenci\u00f3n es de 10, para mi, inmejorable. Son super atentos y tienen en cuenta tus dolencias y tu nivel, y si es necesario te ajustan los ejercicios. Las clases son de pocas personas. La verdad que no me canso de recomendarlo                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocJBrzsKmoXOEjAVbPY3fWqRDpZMWZuBtVTOxCmexDN7HW7v=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Alice\" width=\"56\" height=\"56\" title=\"Alice\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Alice\">Alice<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1776276012\">18:00 15 Apr 26<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Molt professionals, enfocats 100% en la salut i el benestar dels seus alumnes, molt amables i atencio excellent                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocI4wD1U9vsM_BjDkjbDDd8q8l2myYGb3uQiAoEklH1DVGti7w=s120-c-rp-mo-s56-ba6-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Rosemary Bosch\" width=\"56\" height=\"56\" title=\"Rosemary Bosch\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Rosemary Bosch\">Rosemary Bosch<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1765393418\">19:03 10 Dec 25<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Experiencia excelente. Trato muy profesional y cercano. Me sent\u00eda en total confianza con Gloria, que controla much\u00edsimo su \u00e1rea de especialidad y toma el tiempo para contestar a dudas y dar consejos personalizados.Muy agradecida por el buen servicio en todos los centros Aequus.                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocLEjPXW3yX0IXVprGoEwwamWJpe5GIUTVJgcF0iInsG5Q_zoA=s120-c-rp-mo-s56-ba2-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Rachel L\" width=\"56\" height=\"56\" title=\"Rachel L\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJ2SV-IG-TlxIR9ociQUX9DOM\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Rachel L\">Rachel L<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1764680496\">13:01 02 Dec 25<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Ivett la mejor fisio y la mejor profesora de pilates. Estoy encantada con ella.                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjXNT7mQbX0stT39OtgWYJ-NwzlJv083RUG-NERLiPLJoS-_APGMYQ=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Katia Sarraff\" width=\"56\" height=\"56\" title=\"Katia Sarraff\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJ2SV-IG-TlxIR9ociQUX9DOM\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Katia Sarraff\">Katia Sarraff<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1760174259\">09:17 11 Oct 25<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Llevo sufriendo varios meses a causa de una fascitis plantar. He iniciado un tratamiento de radiofrecuencia Indiba y el dolor ha disminuido considerablemente.Ya puedo dar largos paseos!!Ivett es encantadora y una gran fisioterapeuta.Un centro muy profesional. Lo recomiendo.                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocJ22AO2C1r_re5hzYYViHHg08XBGv80OWpZFWU_jijuWANnrA=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Ana Rodriguez\" width=\"56\" height=\"56\" title=\"Ana Rodriguez\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJ2SV-IG-TlxIR9ociQUX9DOM\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Ana Rodriguez\">Ana Rodriguez<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1758836351\">21:39 25 Sep 25<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Es la primera vez que he venido,y el trato a sido inmejorable,ivett me a hecho un tratamiento de radiofrecuencia indiba y a parte de tratarme s\u00faper bien ,se ve que es una gran profesional,volver\u00e9 sin duda.                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocLH_mVNCRsT-1wam2GVUGNbL6LoVin_IaOfksDTMLsygzSZvw=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Cristina Rodriguez Cuesta\" width=\"56\" height=\"56\" title=\"Cristina Rodriguez Cuesta\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJ2SV-IG-TlxIR9ociQUX9DOM\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Cristina Rodriguez Cuesta\">Cristina Rodriguez Cuesta<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1756199208\">09:06 26 Aug 25<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Encantada; un lugar familiar, respetuoso, y donde valoran las necesidades de cada uno. Llevado por profesionales de alt\u00edsima calidad. Sin duda lo recomiendo encarecidamente                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocKGOPKVrpvTZ2va8ur6NqSKpM83BPQv48S8pB6EeCEkoKrM8g=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Maria Villalonga Piera\" width=\"56\" height=\"56\" title=\"Maria Villalonga Piera\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJ2SV-IG-TlxIR9ociQUX9DOM\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Maria Villalonga Piera\">Maria Villalonga Piera<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1754995126\">10:38 12 Aug 25<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Estoy encantada.  Llegu\u00e9 ah\u00ed con un problema lumbar agudo. Me hicieron una valoraci\u00f3n e inici\u00e9 fisioterapia con Ivett. El dolor ya no lo tengo, y estoy por arrancar pilates. Me han tratado de maravilla, lo s\u00faper recomiendo!! Muchas gracias &#x1f90d;                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjUTi9jamU-HPZElDRR5iUG0Cl-HkTRelaFdEwp_iZH7gOsph20=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Mariana Ruiz Barbery\" width=\"56\" height=\"56\" title=\"Mariana Ruiz Barbery\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJ2SV-IG-TlxIR9ociQUX9DOM\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Mariana Ruiz Barbery\">Mariana Ruiz Barbery<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1752660453\">10:07 16 Jul 25<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Desde que comenc\u00e9 a entrenar en Aequus, mi vida ha cambiado. Despu\u00e9s de unos meses, he logrado eliminar los dolores de espalda y cervicales, y lo mejor de todo, \u00a1mis calambres en pies y manos han desaparecido por completo! El equipo es incre\u00edble: profesionales, atentos y siempre motivadores. Gracias a ellos, no solo he mejorado mi salud, sino que tambi\u00e9n he ganado en bienestar. Recomiendo este lugar a todo el que busque un cambio real y duradero.                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjWVtE9AUAnCIwBMSqy_MGlYr60GGh7iy2GIKcVWRG3lDn-AV60=s120-c-rp-mo-s56-ba2-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Silvia Oliden\" width=\"56\" height=\"56\" title=\"Silvia Oliden\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Silvia Oliden\">Silvia Oliden<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1739889888\">14:44 18 Feb 25<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Empez\u00e9 hace dos a\u00f1os con pilates suelo dos veces por semana y estoy encantada, me encuentro mucho mejor, m\u00e1s \u00e1gil y el dolor articular y de espalda han desaparecido. Unos profesionales especializados y que en cada clase eval\u00faan tus capacidades y consiguen motivarte para obtener mejores resultados siempre modificando los ejercicios seg\u00fan las necesidades de cada uno de los clientes. Mi instructora es Luciana y estoy encantada, consigue que cumplamos nuevos objetivos confiando en nuestras capacidades.Muy contenta y lo recomiendo a cualquier persona para mejorar su calidad de vida en el d\u00eda a d\u00eda.                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjU8g2VPSoV1CjOFemXwwPa6eMaiB0SBKjczm8Zn4V9X7oepkcMb=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Andrea S\u00e1nchez Garc\u00eda\" width=\"56\" height=\"56\" title=\"Andrea S\u00e1nchez Garc\u00eda\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Andrea S\u00e1nchez Garc\u00eda\">Andrea S\u00e1nchez Garc\u00eda<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1724939485\">13:51 29 Aug 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        En este centro realic\u00e9 las clases de pilates para embarazadas durante todo mi embarazo (desde la semana 12 hasta el final). Maria Jos\u00e9, mi instructora, nos indicaba diferentes ejercicios en los que trabaj\u00e1bamos todo el cuerpo, siempre adaptados e individualizados si era necesario. Las clases muy amenas y divertidas. Lo recomiendo 100% y repetir\u00eda sin duda en un pr\u00f3ximo embarazo.                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocINedjhp6lI-tQA_DoFjOg1z2_uIs7ykgHCWaDQWQfgLb0pug=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Andrea Valado\" width=\"56\" height=\"56\" title=\"Andrea Valado\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Andrea Valado\">Andrea Valado<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1724874030\">19:40 28 Aug 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"4,google,#777\"><\/div><span class=\"rplg-review-text\">                        Estoy muy contenta con hacer pilates de maquina .Normalmente tengo clase con Maria Jos\u00e9                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocJM1ibAG9fieHP5PXivz6dkfXJuzFvGpnMFvNqcD9KVXZF6ew=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Gracia Bartolome\" width=\"56\" height=\"56\" title=\"Gracia Bartolome\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Gracia Bartolome\">Gracia Bartolome<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1724153095\">11:24 20 Aug 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        He empezado hace poco con mucho dolor de la espalda y poco flexibilidad del cuerpo entero. Dentro de unas semanas ya me siento mucho mejor, las instructores son muy profesionales (tengo classes con Luciana y Mar\u00eda Jos\u00e9) y atentas lo recomendar\u00eda a todos!                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocKoXPZXe5QN5dSTefKmzJbHBFxUkvnz3Kl7Ri6Cmx2tm1v57g=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Will Heneage\" width=\"56\" height=\"56\" title=\"Will Heneage\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Will Heneage\">Will Heneage<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1723533458\">07:17 13 Aug 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"4,google,#777\"><\/div><span class=\"rplg-review-text\">                        Despu\u00e9s de un ataque de ci\u00e1tica hace un a\u00f1o, empez\u00e9 a tomar clases semanales con Mar\u00eda-Jos\u00e9. Me gusta su enfoque gentil y din\u00e1mico. Noto que mis abdominales se han fortalecido y mi postura es mejor. Eleg\u00ed este centro por la atenci\u00f3n que se presta al detalle de los movimientos y la correcci\u00f3n de posturas.                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjWZ8rxSlxuKtqMwe919OJL15jBFAL6iWGgmKvNF6NnlfeD-TYpc=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Julia Lorenceau\" width=\"56\" height=\"56\" title=\"Julia Lorenceau\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Julia Lorenceau\">Julia Lorenceau<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1723208881\">13:08 09 Aug 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Hace m\u00e1s de 1 a\u00f1o que empec\u00e9 con Paloma pilates m\u00e1quina , ha hecho que me guste y que disfrute con las clases, es una excelente profesional que adapta los ejercicios a tus necesidades y capacidades.                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocKvWB77hlwqoEEC8AfnAiK85qi-MjV9hGul1AaIxYtSsepEIA=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Marga Segu\u00ed\" width=\"56\" height=\"56\" title=\"Marga Segu\u00ed\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Marga Segu\u00ed\">Marga Segu\u00ed<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1723191407\">08:16 09 Aug 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        El ambiente genial.    La dedicaci\u00f3n y profesionalidad de las profesoras de pilates excelente.   Mar\u00eda Jos\u00e9 siempre pendiente de todos los alumnos\/as,   con una gran preparaci\u00f3n de sus clases  - que siempre son variadas,  nunca las hace iguales lo cual hace que las clases siempre sean amenas.                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocKRK-CWHFFMhrAw3XxC2KRuPKWDYQUZVHVVW1hm1qe5o4P0pQ=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Rocio Ruiz\" width=\"56\" height=\"56\" title=\"Rocio Ruiz\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Rocio Ruiz\">Rocio Ruiz<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1723151768\">21:16 08 Aug 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Me encanta ir a pilates m\u00e1quina, me siento restaurada cada vez que voy y Paloma mi instructora es un encanto como persona y una excelente profesora, est\u00e1 muy pendiente de los alumnos y te corrige al m\u00ednimo fallo para que puedas realizar bien el ejercicio. Tambi\u00e9n hago menci\u00f3n a Luisiana que cada clase que he hecho con ella me ha encantado su exigencia y su profesionalidad. Gracias por estos buenos profesionales que nos ayudan a cuidar nuestro cuerpo y nuestra postura.                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjVCPC3-ae1AuIzupi96WYIraV7vfAuy_DxNR32DJjSbXsxEmBg=s120-c-rp-mo-s56-ba2-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Desiree Guitian Sarria\" width=\"56\" height=\"56\" title=\"Desiree Guitian Sarria\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Desiree Guitian Sarria\">Desiree Guitian Sarria<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1723147114\">19:58 08 Aug 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        La experiencia muy buena, Ma Jos\u00e9 una gran professional.Sin duda lo recomendaria.                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjV6nUhuhnRlrM5UrzbsibANvSXDjSq0tT-RWY1CEC0uSbZNGS-M=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Espe Gamundi Esteva\" width=\"56\" height=\"56\" title=\"Espe Gamundi Esteva\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Espe Gamundi Esteva\">Espe Gamundi Esteva<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1723139062\">17:44 08 Aug 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Las clases con Maria Jos\u00e9 son cada vez distintas, se curra mucho los ejercicios que son muy originales y siempre te hace trabajar. Crea muy buen ambiente en sus clases y son muy amenas. Una muy buena profesional.                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjUeC42ufhX-Qlkk8pmijf93OhU94e68aSA53KukmyMA_DOI8N8k=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Ana Pilar Gonzalez Castela\" width=\"56\" height=\"56\" title=\"Ana Pilar Gonzalez Castela\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Ana Pilar Gonzalez Castela\">Ana Pilar Gonzalez Castela<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1723133385\">16:09 08 Aug 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        He tenido el placer de tener a  Mar\u00eda Jos\u00e9 acompa\u00f1\u00e1ndome en mi proceso de maternidad. Han sido unos meses maravillosos donde me ha apoyado y ayudado en todo lo que estaba en su mano. He llevado un embarazo buen\u00edsimo, gracias a ella no he tenido ni un solo dolor, todo lo contrario me he encontrado m\u00e1s fuerte y saludable que nunca. Ella ha sido un gran pilar en este camino,  por su profesionalidad que es brutal y por su empat\u00eda y calidez humana. Me acompa\u00f1\u00f3 hasta el d\u00eda de antes de dar a luz.Si volviese a ser mam\u00e1 la elegir\u00eda sin duda!!                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocI7vpzNU1nlt9hxvkDhCyAarS3wtF_eHv3SyxSfGdMqlf_w7g=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Marta Delgado palos\" width=\"56\" height=\"56\" title=\"Marta Delgado palos\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Marta Delgado palos\">Marta Delgado palos<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1723129004\">14:56 08 Aug 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Tuve como instructora de pilates a Mar\u00eda Jos\u00e9 y no puedo estar m\u00e1s contenta. Trato profesional y personal excelente. Acud\u00ed a las clases pre y post parto, y siempre me facilit\u00f3 que pudiera acudir con mi beb\u00e9. Un 10                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocIaCSjAioCHpVR0O9t5gLM9YPTRz82USjrR18cY6RkrHpONyQ=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Cristina Vidal\" width=\"56\" height=\"56\" title=\"Cristina Vidal\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Cristina Vidal\">Cristina Vidal<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1723117817\">11:50 08 Aug 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Empec\u00e9 con Maria Jos\u00e9 hace un a\u00f1o y medio y me enamor\u00e9 del Pilates! Gracias a ella por su puesto. Nunca antes me hab\u00eda gustado. Y ahora, que me he ido de Mallorca, estoy cansada de probar centros y profesoras... no me gusta ninguna!! Tanto el centro c\u00f3mo Maria Jos\u00e9, dejaron el list\u00f3n muy alto!!! Lo recomiendo 100% y encima un precio muy accesible!                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocJSKMoWRBaT15a9JxJ3MqyA_8hGlAvdeDuIo_FyYQwF__8erg=s120-c-rp-mo-s56-ba5-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Marta Mas Gelabert\" width=\"56\" height=\"56\" title=\"Marta Mas Gelabert\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Marta Mas Gelabert\">Marta Mas Gelabert<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1723117745\">11:49 08 Aug 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Es un centro de pilates muy bueno, para personas con problemas de espalda es perfecto. Los monitores son muy majos, te corrigen y est\u00e1n pendientes. Trato muy familiar.                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocLpg6PvntM6XTUm4Oq1YGou7RoFpCBExeYNP48-MGDC2X-oQQ=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Marta Mateu\" width=\"56\" height=\"56\" title=\"Marta Mateu\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Marta Mateu\">Marta Mateu<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1723115369\">11:09 08 Aug 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Yo estoy encantada con Mar\u00eda Jos\u00e9 est\u00e1 siempre pendiente de las dolencias y de c\u00f3mo hacemos los ejercicios .Ella conoce las posibilidades y limitaciones de cada uno\/a .Personaliza y adapta seg\u00fan el caso.Yo voy  por ella!!                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocJY31cKZzRcbxRNUxy2psYJv8fr5JVltEj515tNvIK0HnBsVQ=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"M\u00f3nica Peric\u00e1s\" width=\"56\" height=\"56\" title=\"M\u00f3nica Peric\u00e1s\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"M\u00f3nica Peric\u00e1s\">M\u00f3nica Peric\u00e1s<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1723109684\">09:34 08 Aug 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Empec\u00e9 y ya no puedo dejarlo. Aequus tiene un equipo muy profesional y los locales est\u00e1n bien equipados. Grupos peque\u00f1os y atenci\u00f3n individualizada.He ido a clase con Maria Jos\u00e9 3 a\u00f1os y siempre lo he pasado muy bien. Ha creado siempre un ambiente s\u00faper agradable y entretenido.                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjW_uOR43XQrjQ_CJ5D0T9_QRtEkiyMrQcvZioqWw66tinE6wIB6=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Magdalena Font Bosch\" width=\"56\" height=\"56\" title=\"Magdalena Font Bosch\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Magdalena Font Bosch\">Magdalena Font Bosch<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1723109449\">09:30 08 Aug 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Me encanta mi profesora Mar\u00eda Jos\u00e9, por c\u00f3mo da la clase y su alegr\u00eda contagiosa, el centro en general me gusta mucho                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocKW_HyX06qPeXUS8R8Pr3nySJ5vKFxlX-jDG-I-n3zLCU7srA=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"mariela de la cuesta\" width=\"56\" height=\"56\" title=\"mariela de la cuesta\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"mariela de la cuesta\">mariela de la cuesta<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1723104272\">08:04 08 Aug 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Hace ya a\u00f1os que tuve la suerte de cruzarme en el camino con Guillermo y Elena, propietarios de Estudio Aequus, y junto a su gran equipo de profesionales c\u00f3mo pueden ser Paloma, Brian, Elena, Vicente, entre otros, he recuperado la salud corporal que tanto anhelaba.\u00a1\u00a1\u00a1 Sin duda alguna, ah\u00ed espero continuar muchos a\u00f1os m\u00e1s!!! Gracias equipo!!!                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocKd32YsQJCOlqOOnaDwjMq9Ju88yJAdUciyWEHUwkOZmbh1Kg=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Luciano Carrascosa\" width=\"56\" height=\"56\" title=\"Luciano Carrascosa\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Luciano Carrascosa\">Luciano Carrascosa<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1722504678\">09:31 01 Aug 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Estoy encantada con las clases de pirates m\u00e1quina. Empec\u00e9 hace un mes sin experiencia previa y desde el primer momento mi profe Paloma me integr\u00f3 en la clase, explica todo perfectamente y est\u00e1 siempre pendiente de nosotros para que hagamos correctamente los ejercicios. Os lo recomiendo!                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocLkMAkzy0MWg_m1FdN2if84gIwezwmQ2MvY2fTDU3T0yDtT8Q=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Ali\" width=\"56\" height=\"56\" title=\"Ali\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Ali\">Ali<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1722500999\">08:29 01 Aug 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Agradecer a Vicente,un gran profesional,muy din\u00e1mico y con  much\u00edsima paciencia , darle las gracias por la gran templanza  que tiene con sus alumnos que repite  una y otra vez las mismas cosas hasta que lo entendemos.Gracias y muchas Gracias&#x1fac2;P.D totalmente recomendable ,te encontr\u00e1s mejor tanto f\u00edsico c\u00f3mo mentalmente.                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjXsfEGeHpJPPRIqQXguWU_7wHMkGDShPE9uxTHQj6PiB8nQW7jIPw=s120-c-rp-mo-s56-ba3-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"neus arias ya\u00f1ez\" width=\"56\" height=\"56\" title=\"neus arias ya\u00f1ez\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"neus arias ya\u00f1ez\">neus arias ya\u00f1ez<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1722443337\">16:28 31 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Lo recomiendo 100%! Noto m\u00e1s consciencia sobre mi higiene postural y m\u00fasculos de core m\u00e1s activos. Los instructores Paloma y Bryan son muy buenos!                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjXB20GqGEXSONHYobloMr6L9HFeFXeiqwmlGZPmJjAcv0eoxoS8Xg=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Y H\" width=\"56\" height=\"56\" title=\"Y H\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Y H\">Y H<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1722441656\">16:00 31 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Recomiendo este estudio me parecen que todos son profesionales,mi instructora es Paloma y la recomiendo al 100% a mi me encantan sus clases es ca\u00f1era y le pone pasi\u00f3n y conocimiento, aparte que te cuida mucho.                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjUmQkX9Q2NIUo_mX606ysnUFGBhzT4uYmwVhqOLYvL6U1W-__c=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Nizabeth Reyes\" width=\"56\" height=\"56\" title=\"Nizabeth Reyes\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Nizabeth Reyes\">Nizabeth Reyes<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1722261491\">13:58 29 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Har\u00e1 casi 2 a\u00f1os que empec\u00e9 en Aequus con Paloma y estoy encantada. Es una gran profesional al igual que todos los instructores. He aprendido y mejorado mucho. Un centro muy recomendable                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocKZcXy9fIZGmWRP-zuhh92MCieRYMv3kghrpnvlCPvXBqMUjQ=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"nuria morral boladeras\" width=\"56\" height=\"56\" title=\"nuria morral boladeras\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"nuria morral boladeras\">nuria morral boladeras<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1722198234\">20:23 28 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Llegu\u00e9 al estudio por recomendaci\u00f3n de mi m\u00e9dico de la cl\u00ednica del dolor despu\u00e9s de 5 infiltraciones lumbares y de cadera y despu\u00e9s de dos meses de inactividad por una baja laboral.Mi hicieron un estudio y una valoraci\u00f3n por parte de la fisioterapeuta Ivett y despu\u00e9s Elena me dio una clase para ver mi coordinaci\u00f3n. Desde entonces llevo ya dos meses que he hecho clase con Mar\u00eda Jos\u00e9, Paloma y Luciana y me encuentro mucho mejor. Hay ejercicios que todav\u00eda no puedo hacer pero, creo, que sigo progresando.Mi dolor en la espalda es cr\u00f3nico pero mis instructoras, Paloma y Luciana, ajustan los ejercicios a mi capacidad y al salir de clase me siento mejor y mucho m\u00e1s estirada. La atenci\u00f3n es personalizada y te ayudan a colocar bien la espalda, las rodillas, la pelvis para que no te hagas da\u00f1o.Yo estoy encantada de esta \"inversi\u00f3n en salud\" y la recomiendo a los que tengan problemas de espalda.                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjXJh9V0qgeZwi-m4oLeHjDImYMr0DG-Z1rqHV4tfLk6_1gGw1PH=s120-c-rp-mo-s56-ba3-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Aina Guti\u00e9rrez Coll\" width=\"56\" height=\"56\" title=\"Aina Guti\u00e9rrez Coll\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Aina Guti\u00e9rrez Coll\">Aina Guti\u00e9rrez Coll<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1722015102\">17:31 26 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Hace m\u00e1s de un a\u00f1o q estoy yendo a pilates y estoy muy feliz con los resultados, mi instructora Paloma y Luciana hacen que la clase sea divertida e innovadora siempre. Muy contenta!                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjWkiil94IX4fEMztWOF1L15a-gZLx85kqRehONf6TMy_Vo78W32Mg=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"carla martin\" width=\"56\" height=\"56\" title=\"carla martin\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"carla martin\">carla martin<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1722010396\">16:13 26 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Excelente instructora.muy profesional. En todo momento est\u00e1 pendiente que los ejercicios  se realicen en forma correcta para evitar posible lesiones.totalmente recomendable .                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjV0YjN8R6w0KLPam3O3VcR5-evXK0lCbc7YKRkQxYSyMtR8_REt=s120-c-rp-mo-s56-ba2-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"funes tronca\" width=\"56\" height=\"56\" title=\"funes tronca\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"funes tronca\">funes tronca<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1722008261\">15:37 26 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Desde que comenc\u00e9 hace unos a\u00f1os, han tenido y siguen teniendo muy buenos monitores. Al menos en mi experiencia personal as\u00ed ha sido. Muchas facilidades para adaptarte y recuperar clases que no puedas asistir. Ya el primer d\u00eda de clase not\u00e9 efectos positivos en mi zona lumbar, que es mi \"caballo de batalla\" desde siempre. MUY RECOMENDABLE.                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocKHGA-q_VHoL8VA3UV-NRwX3XRashiVKgtt2kyvA8aiP8BfHg=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Ruben Pelegrina\" width=\"56\" height=\"56\" title=\"Ruben Pelegrina\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Ruben Pelegrina\">Ruben Pelegrina<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1721994958\">11:55 26 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Empec\u00e9 en Estudio Aequus casi por prescripci\u00f3n m\u00e9dica hace 4 a\u00f1os. Ten\u00eda mucha rigidez corporal y mala postura. Adem\u00e1s me estaba enfrentando a la menopausia con todo lo que conlleva corporal y mentalmente. La verdad es que doy gracias de que me recomendasen Aequus. Aqu\u00ed he encontrado una nueva forma de vida, adem\u00e1s de una gran familia. He pasado por muchos instructores y solo tengo palabras buenas para todos ellos. Hago dos clases de pilates maquina y una de suelo. La mayor\u00eda con Paloma, un 100 de chica y profe. Clases muy variadas, para nada repetitivas y muy amenas. As\u00ed que imaginad si lo recomiendo, que estoy en lista de espera para las nuevas clases que combinan pilates y musculaci\u00f3n con otro de los cracks del centro. Brian Delgado. TOTALMENTE RECOMENDABLE.                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjWCb3Ei2BSyj7TRMT-2u2mcbqDFJVKDKUpvlpAE_okj2OSwocpW=s120-c-rp-mo-s56-ba3-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"loly diaz\" width=\"56\" height=\"56\" title=\"loly diaz\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"loly diaz\">loly diaz<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1721985789\">09:23 26 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        El centro Aequus es una maravilla. Todos los profesores son muy profesionales a la vez que cercanos.Ir a Pilates en este centro es lo mejor que he hecho para mi salud                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocLNSD57x_R3fHDF64l5QhLtNdCkxtufUvnSjaa13DdxPvPJ4tP1=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Meritxell Cortey\" width=\"56\" height=\"56\" title=\"Meritxell Cortey\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Meritxell Cortey\">Meritxell Cortey<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1721975997\">06:39 26 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Llevo 6 a\u00f1os recibiendo clases de pilates en Aequs.Me encanta ir tanto por el personal que imparte clases como por el bien que ha hecho a mi espalda el ejercicio tan variado que me proponen.Cinco estrellas &#x2728; para el equipo                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjUg-YJp6T2VpYLTcpiPc5SCvSmmxTh9bwSlzCYbmg1BH27GZJE=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Juan Campos\" width=\"56\" height=\"56\" title=\"Juan Campos\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Juan Campos\">Juan Campos<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1721975423\">06:30 26 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Llevo dos a\u00f1os haciendo pilates con Paloma y mi experiencia no ha podido ser m\u00e1s satisfactoria. He aprendido mucho, sus clases son din\u00e1micas y variadas, te corrige en tus ejercicios para obtener el mejor resultado. La recomendar\u00eda 100%. Tambi\u00e9n quiero mencionar a Luciana, una maravilla de ni\u00f1a que a veces sustituye a Paloma y tambi\u00e9n lo hace de 10.                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocJuBnJ3ScvF0bMVHuKDK9dqrUuxMI-BAmI0zTvOwAx2NNdujQ=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Margarita Torres Elvira\" width=\"56\" height=\"56\" title=\"Margarita Torres Elvira\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Margarita Torres Elvira\">Margarita Torres Elvira<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1721975405\">06:30 26 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Estoy encantado con el centro, las clases son en grupos peque\u00f1os, con lo que te corrigen mucho para hacer bien los ejercicios.Paloma la profe adem\u00e1s de una gran profesional es divertida y las clases se pasan volando.\u00a1Pilates es salud! Lo recomiendo.                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjXsD5foL-5wH6rJUAnXRgRs4681HypQXsvfcKwJH_kK9TJSRXMS=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Antonio Sterling\" width=\"56\" height=\"56\" title=\"Antonio Sterling\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Antonio Sterling\">Antonio Sterling<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1721932784\">18:39 25 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Comenc\u00e9 mis clases de pilates en Aequus hace m\u00e1s o menos un par de a\u00f1os.Con Luciana hace unos meses y ha sido una experiencia incre\u00edble. Desde el primer d\u00eda ha demostrado ser una instructora excepcional, siempre atenta y profesional. Sus clases son din\u00e1micas y adaptadas a mis necesidades, lo que me ha permitido ver resultados notables en poco tiempo. Sin duda, recomiendo a Luciana y Estudio Aequus a cualquiera que busque mejorar su bienestar. \u00a1Much\u00edsimas gracias por todo!                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocLyt5RF4hEKUtqXRRjF0OptwMW3TvwZy9XsymUtsUIgDDrL6w=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Ylenia Scalari\" width=\"56\" height=\"56\" title=\"Ylenia Scalari\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Ylenia Scalari\">Ylenia Scalari<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1721927187\">17:06 25 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Hace medio a\u00f1o que mi monitora de pilates es Paloma. Es joven, pero muy preparada. Tengo varias lesiones cronicas y siempre encuentra un ejercicio adaptado que pueda realizar. Sus clases son entretenidas, variadas y en ocasiones duras y siempre despu\u00e9s de la clase las sensaciones son mucho mejores que al inicio de la misma. Si tuviera que ponerle una nota seria de matr\u00edcula de honor. Gracias \"Palo\".Mi monitora es Maria Jos\u00e9. Sinceramente creo que faltan estrellas para calificarla. Sus clases son  divertidas,  amenas y siempre diferentes. A dia de hoy todav\u00eda no hemos repetido ninguna clase. Creo que todos hemos mejorado mucho.                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocJZAyV-zX6OK7Dzo8XmMd6SVrd2R6KlABVv4qAzZJ3bij4vHQ=s120-c-rp-mo-s56-ba2-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Tomeu Mora Amengual\" width=\"56\" height=\"56\" title=\"Tomeu Mora Amengual\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Tomeu Mora Amengual\">Tomeu Mora Amengual<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1721920531\">15:15 25 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        8 a\u00f1os que nos recomendaron el centro por problemas de espalda, un gran acierto. Los monitores PROFESIONALES, un &#x1f4af;. Ahora es Maria Jos\u00e9 y es un placer estar en sus manos                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocIcafhaJ9PApLxXFLM2FrI6OFB8sFGYG0ouc6WQM7dCaOoJ00A=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Maria Cerda\" width=\"56\" height=\"56\" title=\"Maria Cerda\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Maria Cerda\">Maria Cerda<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1721917646\">14:27 25 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Empec\u00e9 hace unos meses. Nunca hab\u00eda hecho pilates suelo y estoy muy sorprendida con que cada clase sea din\u00e1mica y diferente! Las clases con Paloma son 100 % recomendables.                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjWMRjc6c5tnlaG-LDKpn8ehEdvX05ed9Ul1X1oBY1Y0TGbWUWc=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Victoria Corrales Ortiz\" width=\"56\" height=\"56\" title=\"Victoria Corrales Ortiz\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Victoria Corrales Ortiz\">Victoria Corrales Ortiz<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1721852214\">20:16 24 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Empez\u00e9 hace 2 meses y estoy encantada con el Estudio y los profesores, Luciana, Paloma y Vicente. Muy recomendable!!!                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjV_a2fUc_xCtNdBc_PNhtLgVQ6llCJQJEpAsWMuGyZcC2_KkRXg=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"petra vasutova\" width=\"56\" height=\"56\" title=\"petra vasutova\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"petra vasutova\">petra vasutova<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1721850138\">19:42 24 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        La mejor decisi\u00f3n que tom\u00e9, y ya llevo 2 embarazos, con sus respectivos post partos. Elena en su d\u00eda fue un diez, y ahora Mar\u00eda Jos\u00e9 hace todo muy f\u00e1cil. Clases  muy din\u00e1micas y variadas, que hace que te cundan mucho los entrenos. Mar\u00eda Jos\u00e9 mi profesora actual, tiene una gran calidad humana que hace que te sientas bien durante todo el embarazo. Siempre te ayuda en todo lo que puede y eso se agradece. Clases de m\u00e1quina y suelo completas y equilibradas un centro para ir en cualquier etapa est\u00e9s embarazada o no ya que te dan un asesoramiento integral. Desde mi experiencia puedo decir que me ayud\u00f3 a tener un parto muy disfrutado y una recuperaci\u00f3n m\u00e1s r\u00e1pida de lo esperado . Ahora que ya estoy activa con normalidad puedo decir que no s\u00f3lo me ayuda a nivel f\u00edsico sino tambi\u00e9n a nivel mental, ya que el grupo de clase no puede ser mejor, haciendo que salgas con mucha m\u00e1s energ\u00eda de la que entraste (con dos ni\u00f1os peque\u00f1os una necesita recargar pilas en poco tiempo). Para mi a d\u00eda de hoy es indispensable \ud83d\ude09 intentar sacar el tiempo para ir dos d\u00edas a la semana .                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocIo1LiSlptIcK-hJIA1kE8WGsx--R86Z_N8Gs3RbvratnmjlA=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"M\u00f3nica Fantini\" width=\"56\" height=\"56\" title=\"M\u00f3nica Fantini\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"M\u00f3nica Fantini\">M\u00f3nica Fantini<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1721824542\">12:35 24 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Llevo medio a\u00f1o en este centro y estoy encantada, todos los instructores son muy buenos profesionales, en especial Luciana, siempre pendiente de corregirme sin perder el ritmo ni la sonrisa. Gracias porque he notado un gran cambio al desaparecer el dolor de espalda y logrando todos los objetivos!                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocKDBvkO3JQSBhp4NhhD36yi7_GiGd27no-tGVj7_WuoyNTZPw=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Carmen\" width=\"56\" height=\"56\" title=\"Carmen\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Carmen\">Carmen<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1721739020\">12:50 23 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Llevo dos a\u00f1os practicando pilates m\u00e1quinas y estoy encantada con el centro y especialmente con mi instructora Paloma, que es muy dulce y profesional, haciendo cada clase din\u00e1mica y diferente.                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjUV5fQxjc9txofkHNxK9WXJpF1zupY-uSDR186-aO1xiDlAy-8_Pg=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Carmen Alemany\" width=\"56\" height=\"56\" title=\"Carmen Alemany\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Carmen Alemany\">Carmen Alemany<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1721680312\">20:31 22 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Me encantan las clases de Paloma.A pesar de su juventud es toda una profesional. Sus clases son muy din\u00e1micas, vigilando siempre las posturas, sin duda un diez.                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocK_w9eIq7i2K7Zdw_44MYt4fp5dMWyDCC6ek-t4_j-C4HDGEw=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Mercedes Merino Juncadella\" width=\"56\" height=\"56\" title=\"Mercedes Merino Juncadella\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Mercedes Merino Juncadella\">Mercedes Merino Juncadella<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1721677245\">19:40 22 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Estoy s\u00faper satisfecha en todos los sentidos. Lo recomendar\u00eda, por supuesto. De hecho lo estoy recomendando siempre que tengo ocasi\u00f3n.Mar\u00eda Jos\u00e9 es una estupenda monitora. Amable, simp\u00e1tica, siempre atenta a nuestras necesidades. Exigente en su justa medida. En definitiva, un 10 para ella.                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocLDmdx9yewnLpyeyVPcUDuqFnYkr36e5CXHCMBZStYOSqevug=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Trinidad Rabad\u00e1n\" width=\"56\" height=\"56\" title=\"Trinidad Rabad\u00e1n\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Trinidad Rabad\u00e1n\">Trinidad Rabad\u00e1n<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1721669794\">17:36 22 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Estuve con Miki en varias sesiones de INDIBA y me vinieron muy bien para las molestias que ten\u00eda en la rodilla. La facilidad que daban para concertar las citas tambi\u00e9n era buena                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjU7bWicNAEpp2VkocOUwmYoch21eSDlcWG_KHt__RLo34CBavmq=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Jaime Capell\" width=\"56\" height=\"56\" title=\"Jaime Capell\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJ2SV-IG-TlxIR9ociQUX9DOM\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Jaime Capell\">Jaime Capell<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1721592255\">20:04 21 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Miguel Angel es un fisioterapeuta francamente bien formado y conocedor de las \u00faltimas t\u00e9cnicas de la fisioterapia. Conmigo sus tratamientos han sido muy eficaces                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocK_YagsokOuBQue4rZBDhBS_yfXET8cKYR_tcArMi9R-338rg=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Xisco Calafat\" width=\"56\" height=\"56\" title=\"Xisco Calafat\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJ2SV-IG-TlxIR9ociQUX9DOM\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Xisco Calafat\">Xisco Calafat<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1721414680\">18:44 19 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Un equipo excelente y profesional que te ayudan  en todo momento para alcanzar tus fines                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjXFSEZm6otBrYRQlpLkmUerE4RFGyl7t0yY0EYoYjsfLlRohQMEJA=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Cristina Vivancos\" width=\"56\" height=\"56\" title=\"Cristina Vivancos\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJ2SV-IG-TlxIR9ociQUX9DOM\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Cristina Vivancos\">Cristina Vivancos<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1721406225\">16:23 19 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Excelente centro especializado. Amo ir a mis clases de reformer, adem\u00e1s mi instructora Luciana es incre\u00edble, tremenda profesional, voy notando avances cada semana! Gracias!!                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjUqAMklIbFpM7z3F03doLJXiElitkRY5wKyxW1ZL8Ts3VTbfdN_=s120-c-rp-mo-s56-ba3-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Julieta Andrea Urciuoli Barber\" width=\"56\" height=\"56\" title=\"Julieta Andrea Urciuoli Barber\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Julieta Andrea Urciuoli Barber\">Julieta Andrea Urciuoli Barber<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1721380582\">09:16 19 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Recomiendo pilates en Estudio Aequus 100% Gracias Luciana por haberme descubierto esta disciplina. Vuestras clases son como una fuente de energ\u00eda positiva para mi \ud83d\ude42 Y gracias a los ejercicios y vuestro conocimiento estoy mejorando mi postura y capacidad f\u00edsica.                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjV3SwFdXnwp0itpLVDdSo_6DtEdg1bdP3V2HToAxTXhLYpYw_I=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"mdelosa\" width=\"56\" height=\"56\" title=\"mdelosa\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"mdelosa\">mdelosa<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1721336135\">20:55 18 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Me ha cambiado la vida. Despu\u00e9s de dos embarazos, mi cuerpo a los 42 a\u00f1os estaba no solo est\u00e9ticamente mal, sino tambi\u00e9n con problemas de salud, sobretodo en la zona lumbo-p\u00e9lvica. Empec\u00e9 en este centro por recomendaci\u00f3n de mi m\u00e9dico y despu\u00e9s de dos a\u00f1os practicando pilates m\u00e1quinas mi cuerpo est\u00e1 mejor que cuando ten\u00eda 30 a\u00f1os. Nunca podr\u00e9 agradecer suficientemente a Elena y a todo su equipo por no solo darme fuerza y salud, sino tambi\u00e9n por el trato humano y familiar que te brindan. Mi profe Vicente es s\u00faper profesional y encima te r\u00edes en sus clases, haciendo la hora m\u00e1s amena. Los dem\u00e1s  monitores tambi\u00e9n un diez: Elisa, Mar\u00eda Jos\u00e9, Paloma, Bryan, Luciana, todos absolutamente maravillosos. Se que puedo cambiar clases seg\u00fan me permita mi horario, y siempre me va a cundir la hora.                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocKDCndMtFBJu9M-lqiNps1kxtvVgTPbkWBkgCbj0xl28Y3FWQ=s120-c-rp-mo-s56-ba3-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Regina A\" width=\"56\" height=\"56\" title=\"Regina A\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Regina A\">Regina A<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1721290145\">08:09 18 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Buenos d\u00edas!! Me encantan las clases con Mar\u00eda Jos\u00e9, porque trabajas , te corrije, siempre est\u00e1 atenta y es s\u00faper atenta y sobretodo siempre con un gran sentido del humor.. Me lo paso pipa .Al final 2x 1 . Besitos a todos el equipo , lo hac\u00e9is muy bien . &#x2764;&#xfe0f;                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjXdJ183abTKjUr0hpKIRTnJnhcIJn8ZgHryqARRyzZxEv-lgm6y=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Academia M.Angeles\" width=\"56\" height=\"56\" title=\"Academia M.Angeles\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Academia M.Angeles\">Academia M.Angeles<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1721287490\">07:24 18 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Acudo a este centro desde el inicio del mismo y la calidad y profesionalidad son inmejorablesPor eso no he cambiado sigo en el mismoTodos los instructores de un nivel muy alto !!!                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjXS_aDWU9pjLQCLhg6BaVTw6l7y5c3cvHoGc7Ot0Egd1LMk6Yp2=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Valentina M\" width=\"56\" height=\"56\" title=\"Valentina M\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Valentina M\">Valentina M<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1721230798\">15:39 17 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Descubr\u00ed pilates gracias a este centro y no puedo estar m\u00e1s contenta! Realmente son todos los profesores muy profesionales y atentos. Reina un clima de cordialidad y se nota que todos trabajan a gusto por ayudar a los alumnos. Paloma es muy ca\u00f1era, pero la mejor profe! Sin duda los recomiendo con ojos cerrados.                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocKffsFberPNPXbk4oNwxDrRWSx_VSjMY7hLhjwJcq6K9wbkHg=s120-c-rp-mo-s56-ba3-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Maria Belen Domeniconi\" width=\"56\" height=\"56\" title=\"Maria Belen Domeniconi\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Maria Belen Domeniconi\">Maria Belen Domeniconi<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1721210843\">10:07 17 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Llevo muchos a\u00f1os (desde que comenz\u00f3 su andadura) Estoy encantada porque me viene bien f\u00edsica y mentalmente. Todos los instructores perfectos y pendientes de todos. Mi instructora habitual M\u00aaJos\u00e9 es fant\u00e1stica. Totalmente Recomendable.                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocLaeqLs2VRKazByWdJ85kSyD0EZYuDFXydH1iu7i9yvlLSRIQ=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"josune echave elorza\" width=\"56\" height=\"56\" title=\"josune echave elorza\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"josune echave elorza\">josune echave elorza<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1721202135\">07:42 17 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"4,google,#777\"><\/div><span class=\"rplg-review-text\">                        Empec\u00e9 en aequus despu\u00e9s de la pandemia. Me gusta porque el horario de clases es amplio y los instructores son buenos y no cambian constantemente. Lo recomendaria.                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocI6BAViy4SB05TAq0JosUa-MXfRMB-3lqOIp1rvUUaoJk0nTg=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Carme Alcover\" width=\"56\" height=\"56\" title=\"Carme Alcover\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Carme Alcover\">Carme Alcover<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1721198192\">06:36 17 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Luciana es una instructora muy divertida, paciente y muy amable. Definitivamente las clases con ella me han ayudado mucho y estoy agradecida por su gran labor como profesional y como persona.Es un 20\/10. GRACIAS INFINITAS LU&#x1f64f;&#x1f496;                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjVYggErwNHWdlEIbhpeRn1BMcm_h7fkYbEkCaaF29oTF7n-7uzd=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Ruth Esther De La Rosa Pool\" width=\"56\" height=\"56\" title=\"Ruth Esther De La Rosa Pool\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Ruth Esther De La Rosa Pool\">Ruth Esther De La Rosa Pool<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1721194263\">05:31 17 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        He tenido la fortuna de tener a Mar\u00eda Jos\u00e9 como mi profesora de pilates desde mis inicios, incluso durante mi embarazo, y no podr\u00eda estar m\u00e1s agradecida!Siempre se asegur\u00f3 de adaptar las clases a mis necesidades espec\u00edficas, brind\u00e1ndome la confianza y el apoyo que necesitaba en cada etapa. Adem\u00e1s, sus clases son siempre divertidas y realmente notas su pasi\u00f3n por lo que hace.La recomiendo a cualquiera que busque una instructora de pilates dedicada y conocedora!                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocLOlM0fcsYl2f50OF4Q3Z1O0Gsm-dZb2hjLy9Ge6a98KxFzbg=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Fiorella Scala\" width=\"56\" height=\"56\" title=\"Fiorella Scala\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Fiorella Scala\">Fiorella Scala<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1721164851\">21:20 16 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Estoy en el centro desde su apertura y me mantengo fiel. Por algo ser\u00e1! Creo que he tenido todos los profesores que han pasado por alli y cada uno a su manera ha procurado sacar lo mejor de cada uno de sus alumnos, haci\u00e9ndonos progresar de acuerdo con nuestro potencial y\/o nuestras limitaciones personales.Mar\u00eda Jos\u00e9 es una excelente profesora que nos hace descubrir cada d\u00eda nuevos ejercicios y asi las   clases siempre son m\u00e1s entretenidas.                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocJmQDgAM_QwG2mhRv1MFmoZWUiwtlTLLYrVjvc0PNp2eJHi2A=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Maria Isabel Segu\u00ed Estrany\" width=\"56\" height=\"56\" title=\"Maria Isabel Segu\u00ed Estrany\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Maria Isabel Segu\u00ed Estrany\">Maria Isabel Segu\u00ed Estrany<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1721162025\">20:33 16 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Profe Vicente, excelente profesional y divertido. Me ayud\u00f3 mucho a mejorar mi t\u00e9cnica y progresar.                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocJZooq5htfrgaKrgeLsHOdxBmKZ1n-WOsC4Rm08eAmUIxMiIQ=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Florencia Mori\" width=\"56\" height=\"56\" title=\"Florencia Mori\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Florencia Mori\">Florencia Mori<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1721161718\">20:28 16 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Un centro de pilates con muy buenos profesionales  !!!                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocIqSfx6KnFthg1-5UMQe_vMIRd7h5cDhrKPqBhxiKMdkhhAYA=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"remedios fortuny zaforteza\" width=\"56\" height=\"56\" title=\"remedios fortuny zaforteza\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"remedios fortuny zaforteza\">remedios fortuny zaforteza<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1721158933\">19:42 16 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Llevo a\u00f1os viniendo a este estudio, me parece que todos los profesores son muy buenos y profesionales. En especial Maria Jos\u00e9 combina todo lo que tiene que tener un profesor: t\u00e9cnica, preparaci\u00f3n de las clases y a la vez paciencia, simpat\u00eda, y delicadeza con el alumno.                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocJYSNZUfYE59IGMbCamADuoo-N17DveRrxfIY2G7rAJ_sp-oA=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Jorge\" width=\"56\" height=\"56\" title=\"Jorge\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Jorge\">Jorge<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1721158285\">19:31 16 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Hago pilates m\u00e1quina 2 veces por semana desde hace un a\u00f1o y medio y estoy muy contenta. Me han ayudado a controlar mi dolor lumbar. Paloma muy atenta a que hagamos bien todos los movimientos y un encanto &#x1f60a;                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjWW9ZZS9j4-wOdOO7gYz0Sj0UMAbqtMo0kSQ_Q6t1F5pi6-4iB_=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Mar\u00eda Isabel Exp\u00f3sito\" width=\"56\" height=\"56\" title=\"Mar\u00eda Isabel Exp\u00f3sito\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Mar\u00eda Isabel Exp\u00f3sito\">Mar\u00eda Isabel Exp\u00f3sito<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1721158270\">19:31 16 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Mi experiencia con Luciana como entrenadora de Pilates es fant\u00e1stica. He mejorado mi flexibilidad y me siento mucho mejor.                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocLgppBM-MF0UOwzCut9QMNKd-AD_jV8mI0MtL-K3jp5hYW3Iw=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Silvia Anguera\" width=\"56\" height=\"56\" title=\"Silvia Anguera\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Silvia Anguera\">Silvia Anguera<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1721152976\">18:02 16 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Desde que empec\u00e9 Luciana me ha ayudado mucho para la flexibilidad de mi espalda y la tensi\u00f3n que ten\u00eda en los hombros. Me gusta como lleva sus clases, muy personalizadas y muy atenta a todos.                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocItqn3vBGzXQDSVdd9dEwazGETdSnPI2e8-Wnryw8XFpnbQGg=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"carolina silva\" width=\"56\" height=\"56\" title=\"carolina silva\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"carolina silva\">carolina silva<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1721152924\">18:02 16 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Tengo varias hernias cervicales y una lumbar,  hace dos meses y medio que voy a pilates suelo y me siento bastante mejor que cuando comenc\u00e9, las clases son muy personales, din\u00e1micas y como he comentado antes, efectivas, lo recomiendo 100%.                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocLdMuogEeqTq15Yxa1cVg8DYA8tHbnJm_6iPhAeeaKqATMy=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"adrian bosch ramirez\" width=\"56\" height=\"56\" title=\"adrian bosch ramirez\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"adrian bosch ramirez\">adrian bosch ramirez<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1721150377\">17:19 16 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Llegu\u00e9 de casualidad a este centro, prob\u00e9 una clase y desde entonces no he dejado de ir! Grandes profesionales, sobretodo Vicente &#x1f496;Pilates me ha ido genial para mis problemas de espalda, muy pendientes de corregir posturas y atentos a cualquier molestia que puedas tener para poder adaptarte los ejercicios. Recomiendo al 100%                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjVA80Q0j-_MflDYa39YGwjRj7Vh1hrbn-iqbgKzvTgMNn4ewwvw=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Emili Morell\" width=\"56\" height=\"56\" title=\"Emili Morell\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Emili Morell\">Emili Morell<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1721149605\">17:06 16 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Comenc\u00e9 hace ya m\u00e1s de dos a\u00f1os en el otro centro de aequus y he acabado viniendo a este. Estoy encantad\u00edsimo.Gracias a Mar\u00eda Jos\u00e9 (la instructora con la que entreno habitualmente) mantengo mi espalda sana y libre de los dolores propios de una hernia lumbar. Sus clases de pilates suelo son s\u00faper amenas adem\u00e1s de variadas. No hay dos clases iguales!! Emplea diferente material cada d\u00eda, entrenando diferentes destrezas como la propiocepci\u00f3n, el equilibrio, la fuerza,\u2026 lo mejor de todo es el buen ambiente de sus clases y lo bien que vuelves a casa, tanto f\u00edsica como mentalmente.Siempre que tengo la oportunidad, recomiendo el centro.He entrenado igualmente con Luciana, Elena y Bryan en el pasado, Paloma, Elisa\u2026todos ellos excelentes instructores.Gracias por mantenernos en forma!                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocL5EQCyAYrgPVi1af1imbP5QdJQgu8LGLle6QZFtMhsEKWx=s120-c-rp-mo-s56-ba3-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"A Gs\" width=\"56\" height=\"56\" title=\"A Gs\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"A Gs\">A Gs<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1721147967\">16:39 16 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        El equipo es muy prfesional y los profesores atentos, las clases casi como individuales, las instalaciones son limpias y muy cuidadas. Hago pilates a maquinas y recomendar\u00eda el sitio con 5 estrellas.                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocKhHHPR7CxKIKDXt4UeKrueYLBonU_z-IU6ve8mb07HDqv6=s120-c-rp-mo-s56-ba2-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"marion schweriner\" width=\"56\" height=\"56\" title=\"marion schweriner\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"marion schweriner\">marion schweriner<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1721146976\">16:22 16 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Llevo un a\u00f1o trabajando con Vicente, empec\u00e9  con muchos dolores y tomando mucha medicaci\u00f3n ahora gracias a su gran trabajo y especial cuidado en cada ejercicio que hago puedo decir que estoy mucho mejor y por tanto estoy muy contenta y lo recomiendo a todo el mundo especialmente si necesitas que est\u00e9n pendientes de tu evoluci\u00f3n y me gustar\u00eda a\u00f1adir tambi\u00e9n que hace que cada clase sea un momento divertido y especial!                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjWin_KzvRpjb1sALPPr5yJRiiDWDutjAF-U0YZNii9oaDxRKwzY=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"cristina carrasco\" width=\"56\" height=\"56\" title=\"cristina carrasco\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"cristina carrasco\">cristina carrasco<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1721146951\">16:22 16 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Hace dos a\u00f1os que empec\u00e9 a hacer Pilates en Estudio Aequus, y estoy muy contenta con la decisi\u00f3n, tienen un gran equipo de profesionales. Mi especial agradecimiento para Vicente, mi profesor, sus clases son din\u00e1micas y amenas, est\u00e1 muy pendiente de nosotras en todo momento corrigiendo posturas, adaptando ejercicios si es necesario,... Me siento mucho mejor f\u00edsicamente desde que asisto a ellas. Gracias!&#x1f4aa;&#x1f3fb;                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocIa6wnAJXGprvzpyZpjANnuFxbacw15MOiTJT2Lhkr69Tc7CBY=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"CONCEPCION COLOMA CHICOT\" width=\"56\" height=\"56\" title=\"CONCEPCION COLOMA CHICOT\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"CONCEPCION COLOMA CHICOT\">CONCEPCION COLOMA CHICOT<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1721146240\">16:10 16 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Empec\u00e9 mi andadura en el mundo pilates en la pandemia. Maravilloso descubrimiento. A nivel f\u00edsico y mental he notado un cambio radical desde el trabajo consciente. Mis dos instructores son:-Vicente, aplica pilates puro explicando los ejercicios as\u00ed como las partes del cuerpo implicadas con el fin obtener una buena ejecuci\u00f3n. Las clases son din\u00e1micas y nada aburridas.-Luciana, con ella he descubierto un pilates intenso, me reta a superarme realizando algunas modificaciones m\u00e1s fit sin abandonar la esencia del pilates. Sus clases son din\u00e1micas y siempre incorpora ejercicios nuevos.Es un placer poder disfrutar del pilates de la mano de grandes profesionales &#x1f929;                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjVC8yvs-akubJ4NA5lfzGEApfHCzGHp_e8c42hefyyxYTdwJJe1=s120-c-rp-mo-s56-ba2-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Paz S\" width=\"56\" height=\"56\" title=\"Paz S\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Paz S\">Paz S<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1721145548\">15:59 16 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Hola,hace 11 meses que empec\u00e9 a hacer pilates,en el estudio Aequus; mi monitor, es Vicente,y estoy muy contenta con sus forma de dar las clases ,y el cuidado personal,que tiene con cada uno de nosotros!!!Me siento s\u00faper motivada y  la verdad,comenzar el d\u00eda con una clase de pilates,es energ\u00eda garantizada para todo el dia!!                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocKz7xgVoIT15IoQ9NWbxxBSnEKZW5-M-NbF2A1sTDumSrng-qke=s120-c-rp-mo-s56-ba3-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"cristina minati\" width=\"56\" height=\"56\" title=\"cristina minati\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"cristina minati\">cristina minati<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1721144929\">15:48 16 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Excelente instructor  de pilates de m\u00e1quina.  Me encanta ir a las clases de Vicente semanalmente &#x2764;&#xfe0f;                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocKFa9tlxfnd4MIx2kZkH8o13-2dKQ6wRpzzYkEO8VHeFkuQMg=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"NANCY PUJOL PHELAN\" width=\"56\" height=\"56\" title=\"NANCY PUJOL PHELAN\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"NANCY PUJOL PHELAN\">NANCY PUJOL PHELAN<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1721144657\">15:44 16 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Empec\u00e9 con pilates por recomendaci\u00f3n de mi m\u00e9dica y eleg\u00ed vuestro centro por cercan\u00eda a mi casa. El trato desde el primer d\u00eda fue cercano y cari\u00f1oso, algo que yo valoro mucho. El ambiente es familiar, los monitores muy profesionales y las instalaciones est\u00e1n fenomenal. Estoy muy contenta, seguir\u00e9 con vosotros y lo recomiendo a todos mis conocidos.Ahora mismo mi instructora es Luciana. Un diez, igual que Maria Jos\u00e9 y Paloma.Las tres son grandes maestras y hacen muy agradable el esfuerzo. Ya llevo dos a\u00f1os y mi intenci\u00f3n es no parar.                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocK0simsfcgy2fHU_xBoPk6cdekga67Fphv0hFWF_uv3gumRIw=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Lourdes Pe\u00f1a\" width=\"56\" height=\"56\" title=\"Lourdes Pe\u00f1a\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Lourdes Pe\u00f1a\">Lourdes Pe\u00f1a<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1721139644\">14:20 16 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Luciana la mejor profe!!! Me encantan sus clases                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocJ3V9iDhhqdkHV2NmYLJi8uhTMQsfpz-oIF_bs1SV4BPsdZMw=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Susana O\" width=\"56\" height=\"56\" title=\"Susana O\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Susana O\">Susana O<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1721128929\">11:22 16 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Un diez en interes dedicaci\u00f3n y profesionalidad  por parte de elena. Despues de acudir a varios centros de pilates aequs y Elena son otra cosa y se nota muchisimo                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocIP_c1zhRXhwa6pITdykevfkbTRal4OW8axKUgoB_554UxBgg=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"drpere drpere\" width=\"56\" height=\"56\" title=\"drpere drpere\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"drpere drpere\">drpere drpere<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1721114084\">07:14 16 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Profesora de pilates con m\u00e1quina fant\u00e1stica; sus compa\u00f1eras tambi\u00e9n y el centro fant\u00e1stico                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjU7bWicNAEpp2VkocOUwmYoch21eSDlcWG_KHt__RLo34CBavmq=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Jaime Capell\" width=\"56\" height=\"56\" title=\"Jaime Capell\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Jaime Capell\">Jaime Capell<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1721075269\">20:27 15 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Hace ya un par de a\u00f1os que hago pilates suelo y estoy muy contenta con los resultados. Los grupos son reducidos y eso ayuda a que se pueda hacer el trabajo bien.  Mis instructoras,  Elisa y Paloma son muy buenas profesionales y est\u00e1n pendientes en todo momento de que los ejercicios salgan perfectos y conocen perfectamente aquello que necesita cada alumno\/a. Gracias por vuestra dedicaci\u00f3n!                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocLUMlVfnvlHzxE9nFmdlBFqFzrz1dbI_4PiBStJzHe0OPJJDQ=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Bel\u00e9n Font Gordiola\" width=\"56\" height=\"56\" title=\"Bel\u00e9n Font Gordiola\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Bel\u00e9n Font Gordiola\">Bel\u00e9n Font Gordiola<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1721068812\">18:40 15 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Un centro de pilates magn\u00edfico!! maestros super profesinales y FISIO excelente !!!!                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjWteQJcip-GBS5ervsXGLMN6e3mCwD8sBSIvM09UMqRdspBix1Q9w=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Lara Dom\u00ednguez\" width=\"56\" height=\"56\" title=\"Lara Dom\u00ednguez\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Lara Dom\u00ednguez\">Lara Dom\u00ednguez<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1721061193\">16:33 15 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Hace dos a\u00f1os que voy a Pilates m\u00e1quina dos veces a la semana y seg\u00fan mi experiencia este centro es mucho mejor que otros centros de Pilates que he probado. Mi profesora, Elisa, explica todo muy bien y se asegura de que cada movimiento se realice correctamente. Hago Pilates para evitar lesiones y dolores relacionados con el tenis, y desde que voy a Aequus, no tengo ning\u00fan dolor.Adem\u00e1s, son muy flexibles si necesito recuperar una clase. Los grupos son peque\u00f1os y hay buen ambiente. Ahora ya no podr\u00eda estar sin venir. \u00a1Recomiendo este centro a todos!                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocIFyI3Z4j7CQCVMAjXdBYi_PXF9gUlR5llFUteRAo2VPfoLZA=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Vivian Grunblatt\" width=\"56\" height=\"56\" title=\"Vivian Grunblatt\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Vivian Grunblatt\">Vivian Grunblatt<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1721057762\">15:36 15 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Empec\u00e9 en Aequus Pilates hace casi dos a\u00f1os y me ha cambiado la vida. Elisa,mi instructora, es extraordinaria, me ha corregido posturas que hab\u00eda mal aprendido en otros centros de Pilates.Gracias a Elisa he conseguido mejorar mi conciencia corporal y mi postura. Sus clases son muy din\u00e1micas y siempre salgo como nueva.                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjUyu4TElp2DBmNAWXzx6Bq-ZcTlI9BMfQmA8a9B26JhCwwN5ciy=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Caterina Antich\" width=\"56\" height=\"56\" title=\"Caterina Antich\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Caterina Antich\">Caterina Antich<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1721034042\">09:00 15 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        El centro es muy completo, los profesores son un 10, llevo yendo hace m\u00e1s de un a\u00f1o y estoy encantada. He mejorado mi postura y estoy m\u00e1s \u00e1gil en general.                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocIZuoasMveg720eI4tbPzFfcXNRCe-Qmb7DmfRu4tx9ELwyJg=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Yainely Grande\" width=\"56\" height=\"56\" title=\"Yainely Grande\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Yainely Grande\">Yainely Grande<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1721022694\">05:51 15 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Llevo tres a\u00f1os haciendo pilates en este centro y mi experiencia es muy positiva, tengo problemas de espalda y me ha disminuido mucho el dolor.Sin duda lo recomiendo.                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocIlFDcwbY1JteW-QnSYIu36kxk5BDWo6_XWCLUHhIpuoUvvcw=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Elena Puigcercos\" width=\"56\" height=\"56\" title=\"Elena Puigcercos\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Elena Puigcercos\">Elena Puigcercos<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1720881899\">14:44 13 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        He tenido el placer de conocer Elisa y otros monitores de pilates. Cada uno con su estilo saben encontrar el punto para que tu trabajo en pilates obtenga el m\u00e1ximo rendimiento. Muy muy recomendables, no s\u00f3lo para la gente con lesiones, tambi\u00e9n para mantener y mejorar tu estado f\u00edsico.He acudido a alguna clase con dolores y tras los ejercicios de estiramiento con Elisa he salido como nueva.S\u00faper                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocKtGEUGUcF-jJo-6yf3EptSeO6_gqHtURQa5UXSiHAFGAQ5fdaf=s120-c-rp-mo-s56-ba4-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Noa Cebeiro Garc\u00eda\" width=\"56\" height=\"56\" title=\"Noa Cebeiro Garc\u00eda\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Noa Cebeiro Garc\u00eda\">Noa Cebeiro Garc\u00eda<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1720874177\">12:36 13 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Estudio Aequus es una gran academia de pilates. Concretamente yo como alumno de la instructora Elisa estoy encantado con ella. Las palabras se me quedan cortas para describir su gran profesionalidad pero por poner unas palabras yo dir\u00eda que es: muy cuidadosa, muy amable, atenta y tiene muchos conocimientos tanto de anatom\u00eda como de como trabajar cada parte del cuerpo. Y en mi proceso, siento mejor colocado mi cuerpo y por supuesto mi calidad de vida ha mejorado much\u00edsimo. En resumen yo recomendar\u00eda a Elisa sin dudarlo y por supuesto tambi\u00e9n recomendar\u00eda a esta academia en su conjunto.                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjUDr22xPd-imI4732G0J8J9nDycQn4IzNxkBXENKGFuYEfYMfoU=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Rafael\" width=\"56\" height=\"56\" title=\"Rafael\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Rafael\">Rafael<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1720873852\">12:30 13 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        No paro de decir que desde que empec\u00e9 pilates de m\u00e1quina (octubre 2023) estoy mucho m\u00e1s \u00e1gil\u2026 feliz de ir todas las semanas con Elisa a Aequus!!! Recomendado &#x1f4af;                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocKFk42l8VbWXB8i-m9MLVjt0g3H7El1CZNoUEHgM2YjeUrPSg=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Margarita Tom\u00e1s\" width=\"56\" height=\"56\" title=\"Margarita Tom\u00e1s\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Margarita Tom\u00e1s\">Margarita Tom\u00e1s<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1720872603\">12:10 13 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Despu\u00e9s de casi un a\u00f1o noto muchos cambios, pilates ha contribuido a mi bienestar f\u00edsico y mental. He corregido mi postura, estoy aprendiendo a utilizar mi cuerpo y poco a poco noto zonas m\u00e1s fuertes y definidas.Luciana es una instructora ideal!!! Me encanta su dinamismo en las clases, se me pasa la hora volando y nos reta a la vez que escucha nuestras necesidades. Si pudiera har\u00eda una clase cada d\u00eda con ella! Es lo m\u00e1s&#x2728;                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjX7-sHWmpfk_DoOrvBlwOxNWet7n01UEjeHHQ93LxVHwNz1SpSm=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Judith Mart\u00edn\" width=\"56\" height=\"56\" title=\"Judith Mart\u00edn\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Judith Mart\u00edn\">Judith Mart\u00edn<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1720849170\">05:39 13 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Acud\u00ed a esta cl\u00ednica durante mis vacaciones en Mallorca para seguir tratando una rotura de gemelo interno que me hice una semana antes de viajar. En s\u00f3lo tres sesiones de fisioterapia con la t\u00e9cnica Indiba tuve una mejora sorprendentemente r\u00e1pida, pasando de ir con muletas a la primera sesi\u00f3n a andar pr\u00e1cticamente normal a los tres d\u00edas e incluso empezar a hacer algo de deporte muy suave y sin molestias tras la segunda y tercera sesi\u00f3n.Muy agradecido a la fisioterapeuta Ivett Arroyo por el gran trabajo realizado, las explicaciones detalladas durante las sesiones y los ejercicios que me mand\u00f3 para acelerar la rehabilitaci\u00f3n y fortalecer la zona para prevenir nuevas lesiones. De 10!!!.                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocJ9GRhUQQ0BT9GGbNprdlxBHygh44a5t-zSQ7dAyb7bsfdfCg=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Alfredo\" width=\"56\" height=\"56\" title=\"Alfredo\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJ2SV-IG-TlxIR9ociQUX9DOM\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Alfredo\">Alfredo<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1720342458\">08:54 07 Jul 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        I had a really amazing experience here!I am travelling through Palma and while here I wanted to find the right physio or personal trainer to help me get back moving my body again after struggling a lot this year with a herniated disk and sciatica and having very limited mobility.I was very nervous to come here because I did not want to do the wrong exercises and cause more pain in my back. However immediately after the first session I had with Flor I knew I came to the right place.Flor could not have been more amazing! I did five sessions with her over the course of a week, during which she taught me so many practical ways to improve the way I exercise. She has an incredible knowledge on the human anatomy and overall was such a great teacher. Since my first session here I have regained certain mobility in my leg that I did not have before and I have gained so much confidence in my ability to exercise correctly which is very exciting for me to now feel I have the tools and knowledge to build up my fitness again.The Pilates studio itself is lovely- very big and lots of equipment - all very clean and tidy. The atmosphere is really nice also! The owner was very friendly, a lovely atmosphere from all the teachers and students here.Again would highly recommend!                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocJ4OR7jtT7CGrTj9993tAL_r5fVwU1Sy3I5YyqWqEu_ksSTkw=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"jlouise loshau\" width=\"56\" height=\"56\" title=\"jlouise loshau\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"jlouise loshau\">jlouise loshau<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1718469120\">16:32 15 Jun 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Muy contenta de haber encontrado este centro !Vicente es un gran profesional, que adem\u00e1s de controlar cada postura,para que realices el ejercicio con m\u00e1xima correcci\u00f3n ,hace de sus clases un rato muy ameno y divertido,gracias!!                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjUZyMnNdlNcpP2ARIYHudMBvXMC3tgZoemJOmqpIIAoa45-deQ9=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Liliana Nara\" width=\"56\" height=\"56\" title=\"Liliana Nara\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Liliana Nara\">Liliana Nara<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1715704252\">16:30 14 May 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Hace 10 a\u00f1os tuve un c\u00e1ncer de Ovarios con met\u00e1stasis ,en fin q estuve muy mal ,hoy d\u00eda tengo unos an\u00e1lisis anuales m\u00e1s q buenos y sobre todo con incremento \u00f3seo , gracias a Pilates                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocIrxAQwCv3HnvkSKkVukeMXO6hIdnggkcmsQWLuC___dK72fg=s120-c-rp-mo-s56-ba4-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Blanca Fernandez\" width=\"56\" height=\"56\" title=\"Blanca Fernandez\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJ2SV-IG-TlxIR9ociQUX9DOM\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Blanca Fernandez\">Blanca Fernandez<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1710624144\">21:22 16 Mar 24<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        5 estrellas porque no se pueden dar m\u00e1s. Llevaba meses sufriendo de ac\u00fafenos y con una sola sesi\u00f3n \u00e9stos desaparecieron y de momento no han vuelto. No puedo estar m\u00e1s agradecida y por supuesto lo recomiendo totalmente.                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjVQTg8ydhgdE8ZgQLjD1NtEzzi9xPjeLFiUJD0eNasoyl_jodY=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Maday Lovey\" width=\"56\" height=\"56\" title=\"Maday Lovey\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJ2SV-IG-TlxIR9ociQUX9DOM\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Maday Lovey\">Maday Lovey<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1698437340\">20:09 27 Oct 23<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Hace medio a\u00f1o que me estoy haciendo un tratamiento est\u00e9tico de Indiba con Ivette, con unos resultados muy buenos, estoy notando cambios desde el inicio. Encantada con ella por su calidad humana, profesionalidad y buen trato.                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocJplfTKtreaHb9r6MftT6YfKHlm9-UwZ3CrT_I6nJRU2YFWqg=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Jamnica Chiva\" width=\"56\" height=\"56\" title=\"Jamnica Chiva\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJ2SV-IG-TlxIR9ociQUX9DOM\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Jamnica Chiva\">Jamnica Chiva<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1695568294\">15:11 24 Sep 23<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Tuve una lesi\u00f3n de rotura de peron\u00e9 y gracias al tratamiento y consejos del fisioterapeuta Miki Mendibar la recuperaci\u00f3n ha sido mucho m\u00e1s r\u00e1pida de que esperaba. Lo recomiendo por su profesionalidad y dedicaci\u00f3n. Un diez.                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjXcwSyOP09CMc4egTAJ7XyjqTSSmgrQ_6uaR84V24EuarP4CB8=s120-c-rp-mo-s56-ba2-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Lourdes Escofet Ib\u00e1\u00f1ez\" width=\"56\" height=\"56\" title=\"Lourdes Escofet Ib\u00e1\u00f1ez\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJ2SV-IG-TlxIR9ociQUX9DOM\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Lourdes Escofet Ib\u00e1\u00f1ez\">Lourdes Escofet Ib\u00e1\u00f1ez<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1695234740\">18:32 20 Sep 23<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Mar\u00eda Jos\u00e9 es una profe genial &#x1f60d; y el resto tambi\u00e9n.                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjUPLj5CoPfzaHHEjj3uYjQZiSVclV7aUoM4Uxru-EUsxmx_tDRd=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Caterina Muntaner\" width=\"56\" height=\"56\" title=\"Caterina Muntaner\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Caterina Muntaner\">Caterina Muntaner<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1690375182\">12:39 26 Jul 23<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Llevo recibiendo clases en este estudio desde hace m\u00e1s de tres a\u00f1os, y sigo pensando que AEQUUS es el mejor centro de Pilates que puedes encontrar en Palma.Me gusta que las clases se organicen por niveles, la flexibilidad que te ofrecen para recuperar las clases que no puedes asistir, que las instalaciones siempre est\u00e9n limpias, cuidadas y con todo el material necesario. Pero lo mejor de todo son los monitores por su atenci\u00f3n, conocimientos y profesionalidad.Personalmente, ver como cambia la agilidad y la flexibilidad del cuerpo gracias a la efectividad del ejercicio, y la energ\u00eda con la que sales despu\u00e9s de cada clase, es incre\u00edble!!!Espero poder seguir disfrutando de vuestras clases por mucho tiempo. Gracias. &#x1f64f;                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjXcwSyOP09CMc4egTAJ7XyjqTSSmgrQ_6uaR84V24EuarP4CB8=s120-c-rp-mo-s56-ba2-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Lourdes Escofet Ib\u00e1\u00f1ez\" width=\"56\" height=\"56\" title=\"Lourdes Escofet Ib\u00e1\u00f1ez\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Lourdes Escofet Ib\u00e1\u00f1ez\">Lourdes Escofet Ib\u00e1\u00f1ez<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1690218471\">17:07 24 Jul 23<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Encantada con Estudio Aequus y con Vicente, el instructor! Llevo 3 a\u00f1os, empec\u00e9 cuando estaba embarazada y desde el primer d\u00eda te hacen sentir como en casa, son todos muy amables y facilitan mucho el poder recuperar una clase a la que no hayas podido acudir. Todos los instructores est\u00e1n muy bien preparados, en particular Vicente hace la clase muy amena y din\u00e1mica!                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocKpWjMC7SgJfbg6P1ad-l6XZCKDlgjbdCZNawgpQtFq7oV81g=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Marta M\" width=\"56\" height=\"56\" title=\"Marta M\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Marta M\">Marta M<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1689598372\">12:52 17 Jul 23<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Amabi\u00f1idad, profesionalidad u excel3ncia. No se puede pedir mas.                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjU6tzKBEmcs_LLd9qnrmnIiE5nYlH5hJ3_bRXd2OEqANgmEg9vq=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Josu L\u00f3pez Libano\" width=\"56\" height=\"56\" title=\"Josu L\u00f3pez Libano\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Josu L\u00f3pez Libano\">Josu L\u00f3pez Libano<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1689443710\">17:55 15 Jul 23<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Mi informaci\u00f3n fue en internetLas instalaciones est\u00e1n bienEs cog\u00ed, Pilates maquinas, estoy muy contenta con el profesor .Vicente es un magnifico profesionalTotalmente recomendable                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocLhLzE_ZCGTkmIMamBMFXqg_HgsGhRIlmDC-XZ2gjBvLs8Seg=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"MAICA LOPEZ GUILABERT\" width=\"56\" height=\"56\" title=\"MAICA LOPEZ GUILABERT\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"MAICA LOPEZ GUILABERT\">MAICA LOPEZ GUILABERT<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1689431611\">14:33 15 Jul 23<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Eleg\u00ed este centro porque est\u00e1n especializados en cuidar el cuerpo despu\u00e9s de leer mucho sobre pilates decid\u00ed probar y ahora no puedo vivir sin mis clases de pilates, los dolores desaparecieron y mi movilidad es la de una adolescente. Mi profesor es Vicente este profesor es un buen profesional y sus clases se hacen cortas y amenas.                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocK-vqVvOCDw1NWoQUvpv4X_CjipWUuSs-EnL0S53d2RPmfutQ=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Maria Jes\u00fas G\u00f3mez\" width=\"56\" height=\"56\" title=\"Maria Jes\u00fas G\u00f3mez\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJG7ysimKSlxIRlrzZ40Y5xS0\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Maria Jes\u00fas G\u00f3mez\">Maria Jes\u00fas G\u00f3mez<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1689415364\">10:02 15 Jul 23<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        Fui por dolores y calambres en la zona ci\u00e1tica y piernas, me pusieron en manos de Ivett Fisioterapeuta, y habido un antes y un despu\u00e9s, es cierto que si uno no pone de su parte ea dif\u00edcil avanzar, pero con ellos ha sido realmente un acierto.                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjUqGvyr7CD3hhiegaDCiRmTjdfodm3hNUB6mQjII7CYAQ7KflS1=s120-c-rp-mo-s56-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Pep\" width=\"56\" height=\"56\" title=\"Pep\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJ2SV-IG-TlxIR9ociQUX9DOM\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Pep\">Pep<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1689075814\">11:43 11 Jul 23<\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-slide\"><div class=\"rplg-slider-review\"><div class=\"rplg-box\"><div class=\"rplg-box-content\" ><div class=\"rplg-stars\" data-info=\"5,google,#777\"><\/div><span class=\"rplg-review-text\">                        S\u00faper cercano miky con los tratamientos y con todo lo que te explica a medida que te trata                    <\/span><span class=\"rplg-review-badge\" data-badge=\"google\"><\/span><\/div><\/div><div class=\"rplg-row\"><div class=\"rplg-row-left\"><img decoding=\"async\" src=\"https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png\" data-src=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjXcyFD5yAk13VD024f6gvOI513D9-PBHLaPkE0zb2q_LlNrTMxk=s120-c-rp-mo-s56-ba2-br100\" class=\"rplg-review-avatar rplg-blazy\" alt=\"Bego matas sober\u00f3n\" width=\"56\" height=\"56\" title=\"Bego matas sober\u00f3n\" onerror=\"if(this.src!='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png')this.src='https:\/\/estudioaequus.com\/wp-content\/plugins\/business-reviews-bundle\/assets\/img\/google_avatar.png';\" ><\/div><div class=\"rplg-row-right\"><a href=\"https:\/\/search.google.com\/local\/reviews?placeid=ChIJ2SV-IG-TlxIR9ociQUX9DOM\" class=\"rplg-review-name rplg-trim\" target=\"_blank\" rel=\"noopener\" rel=\"nofollow\"  title=\"Bego matas sober\u00f3n\">Bego matas sober\u00f3n<\/a><div class=\"rplg-review-time rplg-trim\" data-time=\"1689019303\">20:01 10 Jul 23<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"rplgsw-pagination\"><\/div><\/div><div class=\"rplg-slider-prev\"><span>&lsaquo;<\/span><\/div><div class=\"rplg-slider-next\"><span>&rsaquo;<\/span><\/div><\/div><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" alt=\"js_loader\" onload=\"(function(el, data) { var t = setInterval(function () { if (window.rplg_init_slider_theme){ rplg_init_slider_theme(el, data); clearInterval(t); } }, 200); })(this.parentNode, {'speed':5000,'effect':'slide','count':3,'space':40,'pagin':true,'nextprev':true,'mobileBreakpoint':500,'mobileCount':1,'tabletBreakpoint':800,'tabletCount':2,'desktopBreakpoint':1024,'desktopCount':3});\" data-exec=\"false\" width=\"1\" height=\"1\" style=\"display:none\"><\/div>        [\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;rgba(14,50,123,0.8)&#8221; background_image=&#8221;https:\/\/estudioaequus.com\/wp-content\/uploads\/2022\/09\/h6-bckr-1.jpeg&#8221; background_position=&#8221;top_center&#8221; background_blend=&#8221;multiply&#8221; custom_padding=&#8221;|5%|2%|5%|false|true&#8221; top_divider_height=&#8221;50px&#8221; top_divider_flip=&#8221;horizontal&#8221; global_module=&#8221;178&#8243; saved_tabs=&#8221;all&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; z_index=&#8221;2&#8243; width=&#8221;95%&#8221; custom_margin=&#8221;||||true|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;|600|||||||&#8221; text_text_color=&#8221;#FFFFFF&#8221; text_font_size=&#8221;50px&#8221; custom_padding=&#8221;||5%||false|false&#8221; text_font_size_tablet=&#8221;50px&#8221; text_font_size_phone=&#8221;30px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]\n<p style=\"text-align: center;\"><span>Contact with us<\/span><\/p>\n[\/et_pb_text][et_pb_contact_form captcha=&#8221;off&#8221; email=&#8221;info@estudioaequus.com&#8221; custom_message=&#8221;Patient contact details:||et_pb_line_break_holder||||et_pb_line_break_holder||Name: %%Name%%||et_pb_line_line_break_holder||Email: %%Email%%||et_pb_line_break_holder|||Phone: %%telephone%%.&#8221; use_redirect=&#8221;on&#8221; redirect_url=&#8221;https:\/\/estudioaequus.com\/gracias\/&#8221; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; _unique_id=&#8221;1a647530-af77-424b-8de4-409f00de6a2f&#8221; form_field_background_color=&#8221;RGBA(255,255,255,0)&#8221; form_field_text_color=&#8221;#FFFFFF&#8221; form_field_focus_text_color=&#8221;#FFFFFF&#8221; form_field_font_size=&#8221;16px&#8221; custom_button=&#8221;on&#8221; button_text_color=&#8221;#0e327b&#8221; button_bg_color=&#8221;#FFFFFF&#8221; button_border_width=&#8221;0px&#8221; button_border_radius=&#8221;10px&#8221; button_font=&#8221;|||on|||||&#8221; button_use_icon=&#8221;off&#8221; border_width_bottom=&#8221;1px&#8221; border_color_bottom=&#8221;#FFFFFF&#8221; global_colors_info=&#8221;{}&#8221; button_text_color__hover=&#8221;#FFFFFF&#8221; button_text_color__hover_enabled=&#8221;on|hover&#8221; button_bg_color__hover=&#8221;RGBA(255,255,255,0)&#8221; button_bg_color__hover_enabled=&#8221;on|desktop&#8221;][et_pb_contact_field field_id=&#8221;Name&#8221; field_title=&#8221;Name&#8221; _builder_version=&#8221;4.20.0&#8243; custom_css_main_element=&#8221;Max-width: 33%;||Margin-top: -1.5%;&#8221; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;Email&#8221; field_title=&#8221;E-mail address&#8221; field_type=&#8221;email&#8221; _builder_version=&#8221;4.20.0&#8243; custom_css_main_element=&#8221;Max-width: 33%;||Margin-top: -1.5%;&#8221; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;telefono&#8221; field_title=&#8221;Phone&#8221; _builder_version=&#8221;4.20.0&#8243; custom_css_main_element=&#8221;Max-width: 34%;||Float: left;||Margin-top: -1.5%;||Clear: none !important;&#8221; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;recibir_informacion&#8221; field_title=&#8221;receive information&#8221; field_type=&#8221;checkbox&#8221; checkbox_options=&#8221;%91{%22value%22:%22I agree to receive the information that the entity deems appropriate to send me by e-mail or equivalent electronic means of communication. (It is possible to unsubscribe at any time).%22,%22checked%22:0,%22dragID%22:-1,%22link_text%22:%22%22,%22link_url%22:%22%22}%93&#8243; required_mark=&#8221;off&#8221; fullwidth_field=&#8221;on&#8221; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; form_field_text_color=&#8221;#FFFFFF&#8221; custom_margin=&#8221;||||false|false&#8221; custom_css_main_element=&#8221;color:transparent;&#8221; border_width_all=&#8221;1px&#8221; border_color_all=&#8221;#FFFFFF&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;politica_de_privacidad&#8221; field_title=&#8221;privacy policy&#8221; field_type=&#8221;checkbox&#8221; checkbox_options=&#8221;%91{%22value%22:%22I have read and accept the  %22,%22checked%22:0,%22dragID%22:-1,%22link_text%22:%22Privacy Policy%22,%22link_url%22:%22https:\\\/\\\/estudioaequus.com\\\/politica-de-privacidad\\\/%22}%93&#8243; fullwidth_field=&#8221;on&#8221; _builder_version=&#8221;4.20.0&#8243; _module_preset=&#8221;default&#8221; form_field_text_color=&#8221;#FFFFFF&#8221; custom_margin=&#8221;||||false|false&#8221; custom_css_main_element=&#8221;color:transparent;&#8221; border_width_all=&#8221;1px&#8221; border_color_all=&#8221;#FFFFFF&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_contact_field][\/et_pb_contact_form][\/et_pb_column][\/et_pb_row][\/et_pb_section]\n","protected":false},"excerpt":{"rendered":"<p>Who we areEstudio Aequus Who are we? Aequus Studio your specialized Body Health Center in Palma de Mallorca. We are specialists in: RGM Therapy RGM Training &#8220;much more than pilates&#8221;. RGM Physiotherapy: Advanced Physical Therapy Hypopressive gymnastics Nutrition Our main objective is health and body functionality. Our physiotherapists and RGM Training + Pilates instructors are [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","_joinchat":[],"footnotes":""},"class_list":["post-249340","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>About us : Estudio Aequus Mallorca<\/title>\n<meta name=\"description\" content=\"In Estudio Aequus we are experts in physiotherapy and pilates, we have the clinic located in Palma de Mallorca. Ask for information without obligation.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/estudioaequus.com\/en\/about-us\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"About us : Estudio Aequus Mallorca\" \/>\n<meta property=\"og:description\" content=\"In Estudio Aequus we are experts in physiotherapy and pilates, we have the clinic located in Palma de Mallorca. Ask for information without obligation.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/estudioaequus.com\/en\/about-us\/\" \/>\n<meta property=\"og:site_name\" content=\"Estudio aequus\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-29T11:16:53+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"34 minutes\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"About us : Estudio Aequus Mallorca","description":"In Estudio Aequus we are experts in physiotherapy and pilates, we have the clinic located in Palma de Mallorca. Ask for information without obligation.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/estudioaequus.com\/en\/about-us\/","og_locale":"en_US","og_type":"article","og_title":"About us : Estudio Aequus Mallorca","og_description":"In Estudio Aequus we are experts in physiotherapy and pilates, we have the clinic located in Palma de Mallorca. Ask for information without obligation.","og_url":"https:\/\/estudioaequus.com\/en\/about-us\/","og_site_name":"Estudio aequus","article_modified_time":"2024-01-29T11:16:53+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"34 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/estudioaequus.com\/en\/about-us\/","url":"https:\/\/estudioaequus.com\/en\/about-us\/","name":"About us : Estudio Aequus Mallorca","isPartOf":{"@id":"https:\/\/estudioaequus.com\/#website"},"datePublished":"2023-03-10T09:41:44+00:00","dateModified":"2024-01-29T11:16:53+00:00","description":"In Estudio Aequus we are experts in physiotherapy and pilates, we have the clinic located in Palma de Mallorca. Ask for information without obligation.","breadcrumb":{"@id":"https:\/\/estudioaequus.com\/en\/about-us\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/estudioaequus.com\/en\/about-us\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/estudioaequus.com\/en\/about-us\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/estudioaequus.com\/en\/pilates-palma-de-mallorca\/"},{"@type":"ListItem","position":2,"name":"About us"}]},{"@type":"WebSite","@id":"https:\/\/estudioaequus.com\/#website","url":"https:\/\/estudioaequus.com\/","name":"Estudio aequus","description":"Estudio de Pilates en Palma","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/estudioaequus.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/estudioaequus.com\/en\/wp-json\/wp\/v2\/pages\/249340","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/estudioaequus.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/estudioaequus.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/estudioaequus.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/estudioaequus.com\/en\/wp-json\/wp\/v2\/comments?post=249340"}],"version-history":[{"count":7,"href":"https:\/\/estudioaequus.com\/en\/wp-json\/wp\/v2\/pages\/249340\/revisions"}],"predecessor-version":[{"id":249427,"href":"https:\/\/estudioaequus.com\/en\/wp-json\/wp\/v2\/pages\/249340\/revisions\/249427"}],"wp:attachment":[{"href":"https:\/\/estudioaequus.com\/en\/wp-json\/wp\/v2\/media?parent=249340"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}